{"id":109264,"date":"2025-08-21T14:17:18","date_gmt":"2025-08-21T12:17:18","guid":{"rendered":"http:\/\/barazzasrl.it\/fuoriserie\/gallery\/"},"modified":"2025-11-06T16:45:44","modified_gmt":"2025-11-06T15:45:44","slug":"galerie","status":"publish","type":"page","link":"https:\/\/barazzasrl.it\/de\/fuoriserie\/galerie\/","title":{"rendered":"Galerie"},"content":{"rendered":"<section class=\"l-section wpb_row height_medium\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">[vc_custom_heading text=&#8220;INDIVIDUELLE<br \/>\n<em>L\u00d6SUNGEN<\/em> F\u00dcR<br \/>\nELEGANTE UND<br \/>\nSTILVOLLE K\u00dcCHEN&#8220; font_container=&#8220;tag:h1|text_align:left&#8220;]<\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_medium\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p class=\"p1\">Die folgenden <strong>Fotosammlungen zeigen<\/strong> Beispiele f\u00fcr Sonderanfertigungen, die von Barazza realisiert wurden: dank der fruchtbaren Zusammenarbeit mit Architekten, Planern und M\u00f6belfirmen konnten <strong>einzigartige, individuelle und<\/strong> perfekt auf die Bed\u00fcrfnisse des Auftraggebers abgestimmte Einrichtungsl\u00f6sungen kreiert werden.<\/p>\n<p class=\"p1\">Die Vielseitigkeit von Edelstahl, die klaren Linien und die edlen Details erm\u00f6glichen die Herstellung <strong>hochwertiger, ma\u00dfgefertigter Elemente<\/strong>, die sich geschmackvoll in jedes Ambiente einf\u00fcgen und ihm Eleganz und eine pers\u00f6nliche Note verleihen.<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_medium width_full\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-gallery fit_cover type_masonry action_popup_image with_isotope ratio_auto count_67\" style=\"--columns:4;--items-gap:10px;\"><div class=\"w-gallery-list\"><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-dibiessecucine-jrkdesign-2-768x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-dibiessecucine-jrkdesign-2-768x1024.jpg 768w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-dibiessecucine-jrkdesign-2-225x300.jpg 225w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-dibiessecucine-jrkdesign-2-135x180.jpg 135w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-dibiessecucine-jrkdesign-2.jpg 998w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/div><a class=\"w-gallery-item-link\" aria-label=\"barazza-realizzazioni-fuoriserie-dibiessecucine-jrkdesign-2\" href=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-dibiessecucine-jrkdesign-2.jpg\"><\/a><\/div><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"835\" height=\"1024\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-arrital-4-835x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-arrital-4-835x1024.jpg 835w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-arrital-4-245x300.jpg 245w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-arrital-4-147x180.jpg 147w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-arrital-4.jpg 1174w\" sizes=\"auto, (max-width: 835px) 100vw, 835px\" \/><\/div><a class=\"w-gallery-item-link\" aria-label=\"barazza-realizzazioni-fuoriserie-arrital-4\" href=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-arrital-4.jpg\"><\/a><\/div><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-dibiessecucine-jrkdesign-5.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-dibiessecucine-jrkdesign-5.jpg 768w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-dibiessecucine-jrkdesign-5-225x300.jpg 225w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-dibiessecucine-jrkdesign-5-135x180.jpg 135w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/div><a class=\"w-gallery-item-link\" aria-label=\"barazza-realizzazioni-fuoriserie-dibiessecucine-jrkdesign-5\" href=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-dibiessecucine-jrkdesign-5.jpg\"><\/a><\/div><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-doimocucine-2-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-doimocucine-2-1024x683.jpg 1024w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-doimocucine-2-300x200.jpg 300w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-doimocucine-2-180x120.jpg 180w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-doimocucine-2.jpg 1422w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><a class=\"w-gallery-item-link\" aria-label=\"barazza-realizzazioni-fuoriserie-doimocucine-2\" href=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-doimocucine-2.jpg\"><\/a><\/div><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"682\" height=\"1024\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-doimocucine-3-682x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-doimocucine-3-682x1024.jpg 682w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-doimocucine-3-200x300.jpg 200w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-doimocucine-3-120x180.jpg 120w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-doimocucine-3.jpg 1158w\" sizes=\"auto, (max-width: 682px) 100vw, 682px\" \/><\/div><a class=\"w-gallery-item-link\" aria-label=\"barazza-realizzazioni-fuoriserie-doimocucine-3\" href=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-doimocucine-3.jpg\"><\/a><\/div><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"960\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-arrital-3.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-arrital-3.jpg 960w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-arrital-3-300x300.jpg 300w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-arrital-3-90x90.jpg 90w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-arrital-3-180x180.jpg 180w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><\/div><a class=\"w-gallery-item-link\" aria-label=\"barazza-realizzazioni-fuoriserie-arrital-3\" href=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-arrital-3.jpg\"><\/a><\/div><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"835\" height=\"1024\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-arrital-2-835x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-arrital-2-835x1024.jpg 835w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-arrital-2-245x300.jpg 245w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-arrital-2-147x180.jpg 147w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-arrital-2.jpg 1174w\" sizes=\"auto, (max-width: 835px) 100vw, 835px\" \/><\/div><a class=\"w-gallery-item-link\" aria-label=\"barazza-realizzazioni-fuoriserie-arrital-2\" href=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-arrital-2.jpg\"><\/a><\/div><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-arrital-1-1024x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-arrital-1-1024x1024.jpg 1024w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-arrital-1-300x300.jpg 300w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-arrital-1-90x90.jpg 90w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-arrital-1-180x180.jpg 180w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-arrital-1.jpg 1440w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><a class=\"w-gallery-item-link\" aria-label=\"barazza-realizzazioni-fuoriserie-arrital-1\" href=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-arrital-1.jpg\"><\/a><\/div><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"608\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-valdesign-1024x608.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-valdesign-1024x608.jpg 1024w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-valdesign-300x178.jpg 300w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-valdesign-180x107.jpg 180w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-valdesign.jpg 1440w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><a class=\"w-gallery-item-link\" aria-label=\"barazza-realizzazioni-fuoriserie-valdesign\" href=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-valdesign.jpg\"><\/a><\/div><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-fantinsrl-6-768x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-fantinsrl-6-768x1024.jpg 768w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-fantinsrl-6-225x300.jpg 225w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-fantinsrl-6-135x180.jpg 135w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-fantinsrl-6.jpg 1000w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/div><a class=\"w-gallery-item-link\" aria-label=\"barazza-realizzazioni-fuoriserie-fantinsrl-6\" href=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-fantinsrl-6.jpg\"><\/a><\/div><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-fantinsrl-5-1024x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-fantinsrl-5-1024x1024.jpg 1024w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-fantinsrl-5-300x300.jpg 300w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-fantinsrl-5-90x90.jpg 90w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-fantinsrl-5-180x180.jpg 180w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-fantinsrl-5.jpg 1125w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><a class=\"w-gallery-item-link\" aria-label=\"barazza-realizzazioni-fuoriserie-fantinsrl-5\" href=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-fantinsrl-5.jpg\"><\/a><\/div><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"920\" height=\"920\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-fantinsrl-4.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-fantinsrl-4.jpg 920w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-fantinsrl-4-300x300.jpg 300w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-fantinsrl-4-90x90.jpg 90w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-fantinsrl-4-180x180.jpg 180w\" sizes=\"auto, (max-width: 920px) 100vw, 920px\" \/><\/div><a class=\"w-gallery-item-link\" aria-label=\"barazza-realizzazioni-fuoriserie-fantinsrl-4\" href=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-fantinsrl-4.jpg\"><\/a><\/div><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"1000\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-fantinsrl-3.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-fantinsrl-3.jpg 1000w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-fantinsrl-3-300x300.jpg 300w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-fantinsrl-3-90x90.jpg 90w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-fantinsrl-3-180x180.jpg 180w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/div><a class=\"w-gallery-item-link\" aria-label=\"barazza-realizzazioni-fuoriserie-fantinsrl-3\" href=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-fantinsrl-3.jpg\"><\/a><\/div><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"785\" height=\"1024\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-fantinsrl-1-785x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-fantinsrl-1-785x1024.jpg 785w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-fantinsrl-1-230x300.jpg 230w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-fantinsrl-1-138x180.jpg 138w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-fantinsrl-1.jpg 800w\" sizes=\"auto, (max-width: 785px) 100vw, 785px\" \/><\/div><a class=\"w-gallery-item-link\" aria-label=\"barazza-realizzazioni-fuoriserie-fantinsrl-1\" href=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-fantinsrl-1.jpg\"><\/a><\/div><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"768\" height=\"1024\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-elmarcucine-768x1024.jpg\" class=\"attachment-large size-large\" alt=\"\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-elmarcucine-768x1024.jpg 768w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-elmarcucine-225x300.jpg 225w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-elmarcucine-135x180.jpg 135w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-elmarcucine.jpg 1399w\" sizes=\"auto, (max-width: 768px) 100vw, 768px\" \/><\/div><a class=\"w-gallery-item-link\" aria-label=\"barazza-realizzazioni-fuoriserie-elmarcucine\" href=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/09\/barazza-realizzazioni-fuoriserie-elmarcucine.jpg\"><\/a><\/div><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"683\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/barazza-realizzazioni-fuoriserie-zampieri-2-1024x683.jpg\" class=\"attachment-large size-large\" alt=\"Dettaglio di un piano in acciaio, montato su un mobile in legno, sul quale figura un piano cottura a gas affiancato da un tagliere in legno su cui poggiano delle cipolle e un coltello\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/barazza-realizzazioni-fuoriserie-zampieri-2-1024x683.jpg 1024w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/barazza-realizzazioni-fuoriserie-zampieri-2-300x200.jpg 300w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/barazza-realizzazioni-fuoriserie-zampieri-2-180x120.jpg 180w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/barazza-realizzazioni-fuoriserie-zampieri-2-scaled.jpg 1980w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><a class=\"w-gallery-item-link\" aria-label=\"Dettaglio di un piano in acciaio, montato su un mobile in legno, sul quale figura un piano cottura a gas affiancato da un tagliere in legno su cui poggiano delle cipolle e un coltello \" href=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/barazza-realizzazioni-fuoriserie-zampieri-2-scaled.jpg\"><\/a><\/div><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"739\" height=\"1024\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/barazza-realizzazioni-fuoriserie-img5_05933-739x1024.jpg\" class=\"attachment-large size-large\" alt=\"Vista di una cucina in legno che mostra una parete attrezzata con mobilio, forni e un piano montato su armadietti.\nNel centro c&#039;\u00e8 un&#039;isola, sormontata da una cappa aspirante in acciaio, sulla quale poggiano un lavello a vasca quadra e un piano a induzione\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/barazza-realizzazioni-fuoriserie-img5_05933-739x1024.jpg 739w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/barazza-realizzazioni-fuoriserie-img5_05933-217x300.jpg 217w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/barazza-realizzazioni-fuoriserie-img5_05933-130x180.jpg 130w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/barazza-realizzazioni-fuoriserie-img5_05933.jpg 1011w\" sizes=\"auto, (max-width: 739px) 100vw, 739px\" \/><\/div><a class=\"w-gallery-item-link\" aria-label=\"Vista di una cucina in legno che mostra una parete attrezzata con mobilio, forni e un piano montato su armadietti.\nNel centro c&#039;\u00e8 un&#039;isola, sormontata da una cappa aspirante in acciaio, sulla quale poggiano un lavello a vasca quadra e un piano a induzione \" href=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/barazza-realizzazioni-fuoriserie-img5_05933.jpg\"><\/a><\/div><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"643\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/barazza-realizzazioni-fuoriserie-euromobil-2-1024x643.jpg\" class=\"attachment-large size-large\" alt=\"Dettaglio di un mobile a cassettiera aperto che mostra i contenuti dei vari cassetti, quali stoviglie e accessori per cucina vari\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/barazza-realizzazioni-fuoriserie-euromobil-2-1024x643.jpg 1024w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/barazza-realizzazioni-fuoriserie-euromobil-2-300x188.jpg 300w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/barazza-realizzazioni-fuoriserie-euromobil-2-180x113.jpg 180w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/barazza-realizzazioni-fuoriserie-euromobil-2-scaled.jpg 1980w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><a class=\"w-gallery-item-link\" aria-label=\"Dettaglio di un mobile a cassettiera aperto che mostra i contenuti dei vari cassetti, quali stoviglie e accessori per cucina vari \" href=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/barazza-realizzazioni-fuoriserie-euromobil-2-scaled.jpg\"><\/a><\/div><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"682\" height=\"1024\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/barazza-realizzazioni-fuoriserie-0863-jnicolabombassei2017-682x1024.jpg\" class=\"attachment-large size-large\" alt=\"Dettaglio di una cucina dove si pu\u00f2 notare un piano cottura a gas in acciaio, sormontato da una cappa aspirante, davanti al quale \u00e8 posto un piano in legno.\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/barazza-realizzazioni-fuoriserie-0863-jnicolabombassei2017-682x1024.jpg 682w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/barazza-realizzazioni-fuoriserie-0863-jnicolabombassei2017-200x300.jpg 200w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/barazza-realizzazioni-fuoriserie-0863-jnicolabombassei2017-120x180.jpg 120w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/barazza-realizzazioni-fuoriserie-0863-jnicolabombassei2017.jpg 933w\" sizes=\"auto, (max-width: 682px) 100vw, 682px\" \/><\/div><a class=\"w-gallery-item-link\" aria-label=\"Dettaglio di una cucina dove si pu\u00f2 notare un piano cottura a gas in acciaio, sormontato da una cappa aspirante, davanti al quale \u00e8 posto un piano in legno. \n\" href=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/barazza-realizzazioni-fuoriserie-0863-jnicolabombassei2017.jpg\"><\/a><\/div><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"889\" height=\"1024\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/barazza-realizzazioni-fuoriserie-19017_mittel_cucine-comp1_v08-889x1024.jpg\" class=\"attachment-large size-large\" alt=\"Vista di una cucina sul cui sfondo si pu\u00f2 notare una parete a scaffali sulla quale poggiano degli oggetti decorativi e, in primo piano, un&#039;isola in acciaio sulla quale poggiano un lavello a vasca quadra e un piano cottura a gas sormontato da una cappa aspirante\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/barazza-realizzazioni-fuoriserie-19017_mittel_cucine-comp1_v08-889x1024.jpg 889w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/barazza-realizzazioni-fuoriserie-19017_mittel_cucine-comp1_v08-260x300.jpg 260w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/barazza-realizzazioni-fuoriserie-19017_mittel_cucine-comp1_v08-156x180.jpg 156w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/barazza-realizzazioni-fuoriserie-19017_mittel_cucine-comp1_v08.jpg 1215w\" sizes=\"auto, (max-width: 889px) 100vw, 889px\" \/><\/div><a class=\"w-gallery-item-link\" aria-label=\"Vista di una cucina sul cui sfondo si pu\u00f2 notare una parete a scaffali sulla quale poggiano degli oggetti decorativi e, in primo piano, un&#039;isola in acciaio sulla quale poggiano un lavello a vasca quadra e un piano cottura a gas sormontato da una cappa aspirante \" href=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/barazza-realizzazioni-fuoriserie-19017_mittel_cucine-comp1_v08.jpg\"><\/a><\/div><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"661\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/barazza-realizzazioni-fuoriserie-arredo3-1-1024x661.jpg\" class=\"attachment-large size-large\" alt=\"Vista di una cucina\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/barazza-realizzazioni-fuoriserie-arredo3-1-1024x661.jpg 1024w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/barazza-realizzazioni-fuoriserie-arredo3-1-300x194.jpg 300w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/barazza-realizzazioni-fuoriserie-arredo3-1-180x116.jpg 180w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/barazza-realizzazioni-fuoriserie-arredo3-1-scaled.jpg 1980w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><a class=\"w-gallery-item-link\" aria-label=\"Vista di una cucina \" href=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/barazza-realizzazioni-fuoriserie-arredo3-1-scaled.jpg\"><\/a><\/div><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"788\" height=\"1024\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/barazza-realizzazioni-fuoriserie-arrital-1-788x1024.jpg\" class=\"attachment-large size-large\" alt=\"Vista di una cucina in legno e acciaio sul quale sfondo si nota una parete con scaffalature in legno su cui poggiano libri e oggetti di decoro affiancate da frigoriferi a parete. \nIn centro figura un&#039;isola angolare sormontata da una cappa e dei lampadiri, di fronte alla quale sono posti due sgabelli, sui cui poggiano un piano a induzione e un lavello\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/barazza-realizzazioni-fuoriserie-arrital-1-788x1024.jpg 788w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/barazza-realizzazioni-fuoriserie-arrital-1-231x300.jpg 231w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/barazza-realizzazioni-fuoriserie-arrital-1-138x180.jpg 138w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/barazza-realizzazioni-fuoriserie-arrital-1.jpg 1077w\" sizes=\"auto, (max-width: 788px) 100vw, 788px\" \/><\/div><a class=\"w-gallery-item-link\" aria-label=\"Vista di una cucina in legno e acciaio sul quale sfondo si nota una parete con scaffalature in legno su cui poggiano libri e oggetti di decoro affiancate da frigoriferi a parete. \nIn centro figura un&#039;isola angolare sormontata da una cappa e dei lampadiri, di fronte alla quale sono posti due sgabelli, sui cui poggiano un piano a induzione e un lavello \" href=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/barazza-realizzazioni-fuoriserie-arrital-1.jpg\"><\/a><\/div><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"592\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/barazza-realizzazioni-fuoriserie-arrital-2-1024x592.jpg\" class=\"attachment-large size-large\" alt=\"Vista frontale di una cucina a parete nella quale figurano un piano, montato su armadietti, su quale poggiano un lavello a due vasche quadre e un piano a induzione sormontato da una cappa aspirante.\nSopra alla cucina sono montati degli stipetti a parete\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/barazza-realizzazioni-fuoriserie-arrital-2-1024x592.jpg 1024w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/barazza-realizzazioni-fuoriserie-arrital-2-300x173.jpg 300w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/barazza-realizzazioni-fuoriserie-arrital-2-180x104.jpg 180w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/barazza-realizzazioni-fuoriserie-arrital-2-scaled.jpg 1980w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/div><a class=\"w-gallery-item-link\" aria-label=\"Vista frontale di una cucina a parete nella quale figurano un piano, montato su armadietti, su quale poggiano un lavello a due vasche quadre e un piano a induzione sormontato da una cappa aspirante.\nSopra alla cucina sono montati degli stipetti a parete \" href=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/barazza-realizzazioni-fuoriserie-arrital-2-scaled.jpg\"><\/a><\/div><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/barazza-realizzazioni-fuoriserie-arrital-13-819x1024.jpg\" class=\"attachment-large size-large\" alt=\"Dettaglio di una cucina che mostra un piano in acciaio montato su un mobile in legno sul quale poggia un accessorio di cottura e degli oggetti decorativi e, dietro il quale, figura una parete attrezzata con armadietti e accessori\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/barazza-realizzazioni-fuoriserie-arrital-13-819x1024.jpg 819w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/barazza-realizzazioni-fuoriserie-arrital-13-240x300.jpg 240w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/barazza-realizzazioni-fuoriserie-arrital-13-144x180.jpg 144w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/barazza-realizzazioni-fuoriserie-arrital-13.jpg 1120w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/><\/div><a class=\"w-gallery-item-link\" aria-label=\"Dettaglio di una cucina che mostra un piano in acciaio montato su un mobile in legno sul quale poggia un accessorio di cottura e degli oggetti decorativi e, dietro il quale, figura una parete attrezzata con armadietti e accessori \" href=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/barazza-realizzazioni-fuoriserie-arrital-13.jpg\"><\/a><\/div><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"732\" height=\"1000\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/arrital4.jpg\" class=\"attachment-large size-large\" alt=\"Dettaglio di una cucina in cui si vede un&#039;isola in legno con piano in acciaio su cui figurano un piano di cottura a gas con sopra una padella e, posto di fronte separato da un divisorio in vetro, un lavello a due vasche quadre\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/arrital4.jpg 732w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/arrital4-220x300.jpg 220w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/arrital4-132x180.jpg 132w\" sizes=\"auto, (max-width: 732px) 100vw, 732px\" \/><\/div><a class=\"w-gallery-item-link\" aria-label=\"Dettaglio di una cucina in cui si vede un&#039;isola in legno con piano in acciaio su cui figurano un piano di cottura a gas con sopra una padella e, posto di fronte separato da un divisorio in vetro, un lavello a due vasche quadre\" href=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/arrital4.jpg\"><\/a><\/div><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"819\" height=\"1024\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/barazza-realizzazioni-fuoriserie-arrital10-819x1024.jpg\" class=\"attachment-large size-large\" alt=\"Dettaglio di un piano da cucina in legno con inserti in acciaio sul quale poggiano un libro aperto e una pentola. \nSullo sfondo si intravedono delle scale\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/barazza-realizzazioni-fuoriserie-arrital10-819x1024.jpg 819w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/barazza-realizzazioni-fuoriserie-arrital10-240x300.jpg 240w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/barazza-realizzazioni-fuoriserie-arrital10-144x180.jpg 144w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/barazza-realizzazioni-fuoriserie-arrital10.jpg 1120w\" sizes=\"auto, (max-width: 819px) 100vw, 819px\" \/><\/div><a class=\"w-gallery-item-link\" aria-label=\"Dettaglio di un piano da cucina in legno con inserti in acciaio sul quale poggiano un libro aperto e una pentola. \nSullo sfondo si intravedono delle scale\" href=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/barazza-realizzazioni-fuoriserie-arrital10.jpg\"><\/a><\/div><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"505\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/arrital1.jpg\" class=\"attachment-large size-large\" alt=\"Vista frontale di una cucina nella quale figurano degli armadietti a parete nei quali sono incassati due forni, un&#039;isola centrale sulla quale sono poggiati un piano cottura a gas e un lavello, separati da un divisorio in vetro, e un tavolo con sedie. \nSullo sfondo c&#039;\u00e8 una vetrata con vista sul paesaggio esterno\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/arrital1.jpg 1000w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/arrital1-300x152.jpg 300w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/arrital1-180x91.jpg 180w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/div><a class=\"w-gallery-item-link\" aria-label=\"Vista frontale di una cucina nella quale figurano degli armadietti a parete nei quali sono incassati due forni, un&#039;isola centrale sulla quale sono poggiati un piano cottura a gas e un lavello, separati da un divisorio in vetro, e un tavolo con sedie. \nSullo sfondo c&#039;\u00e8 una vetrata con vista sul paesaggio esterno \" href=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/arrital1.jpg\"><\/a><\/div><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"667\" height=\"1000\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/arrital2.jpg\" class=\"attachment-large size-large\" alt=\"Dettaglio di un piano in acciaio su cui figura la scritta &quot;Arrital by k_culture BARAZZA&quot;\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/arrital2.jpg 667w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/arrital2-200x300.jpg 200w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/arrital2-120x180.jpg 120w\" sizes=\"auto, (max-width: 667px) 100vw, 667px\" \/><\/div><a class=\"w-gallery-item-link\" aria-label=\"Dettaglio di un piano in acciaio su cui figura la scritta &quot;Arrital by k_culture BARAZZA&quot;\" href=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/arrital2.jpg\"><\/a><\/div><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"750\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/arrital3.jpg\" class=\"attachment-large size-large\" alt=\"Dettaglio di una cucina che mostra due piani, in acciaio e granito, poggiati su armadietti. \nI piani supportano, rispettivamente, un lavello a due vasche quadre e tre piani cottura, due a gas e uno a induzione\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/arrital3.jpg 1000w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/arrital3-300x225.jpg 300w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/arrital3-180x135.jpg 180w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/div><a class=\"w-gallery-item-link\" aria-label=\"Dettaglio di una cucina che mostra due piani, in acciaio e granito, poggiati su armadietti. \nI piani supportano, rispettivamente, un lavello a due vasche quadre e tre piani cottura, due a gas e uno a induzione \" href=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/arrital3.jpg\"><\/a><\/div><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"750\" height=\"1024\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/barazza-realizzazioni-fuoriserie-arrital-750x1024.jpg\" class=\"attachment-large size-large\" alt=\"Dettaglio di una cucina in cui si vede un&#039;isola in legno con piano in acciaio su cui figurano un piano di cottura a gas con sopra una padella e, posto di fronte separato da un divisorio in vetro, un lavello a due vasche quadre\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/barazza-realizzazioni-fuoriserie-arrital-750x1024.jpg 750w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/barazza-realizzazioni-fuoriserie-arrital-220x300.jpg 220w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/barazza-realizzazioni-fuoriserie-arrital-132x180.jpg 132w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/barazza-realizzazioni-fuoriserie-arrital.jpg 1025w\" sizes=\"auto, (max-width: 750px) 100vw, 750px\" \/><\/div><a class=\"w-gallery-item-link\" aria-label=\"Dettaglio di una cucina in cui si vede un&#039;isola in legno con piano in acciaio su cui figurano un piano di cottura a gas con sopra una padella e, posto di fronte separato da un divisorio in vetro, un lavello a due vasche quadre \" href=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/barazza-realizzazioni-fuoriserie-arrital.jpg\"><\/a><\/div><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"665\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/aura1.jpg\" class=\"attachment-large size-large\" alt=\"Piano cottura in acciaio a due piastre posizionato all&#039;aperto\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/aura1.jpg 1000w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/aura1-300x200.jpg 300w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/aura1-180x120.jpg 180w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/div><a class=\"w-gallery-item-link\" aria-label=\"Piano cottura in acciaio a due piastre posizionato all&#039;aperto \" href=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/aura1.jpg\"><\/a><\/div><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"665\" height=\"1000\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/aura2.jpg\" class=\"attachment-large size-large\" alt=\"Piano cottura in acciaio posizionato all&#039;aperto fra due alberi\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/aura2.jpg 665w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/aura2-200x300.jpg 200w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/aura2-120x180.jpg 120w\" sizes=\"auto, (max-width: 665px) 100vw, 665px\" \/><\/div><a class=\"w-gallery-item-link\" aria-label=\"Piano cottura in acciaio posizionato all&#039;aperto fra due alberi \" href=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/aura2.jpg\"><\/a><\/div><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"707\" height=\"1000\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/aura3.jpg\" class=\"attachment-large size-large\" alt=\"Piano cottura in acciaio a due piastre posizionato all&#039;aperto\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/aura3.jpg 707w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/aura3-212x300.jpg 212w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/aura3-127x180.jpg 127w\" sizes=\"auto, (max-width: 707px) 100vw, 707px\" \/><\/div><a class=\"w-gallery-item-link\" aria-label=\"Piano cottura in acciaio a due piastre posizionato all&#039;aperto \" href=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/aura3.jpg\"><\/a><\/div><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"800\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/dibiesse1.jpg\" class=\"attachment-large size-large\" alt=\"Dettaglio di una cucina su cui poggia un piano in acciaio dove si affiancano un lavello a vasca circolare e un piano cottura a gas su cui poggia una pentola. \nDietro al piano in acciaio si notano una cappa aspirante montata a muro e una paretina con scaffali con gocciolatoio\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/dibiesse1.jpg 600w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/dibiesse1-225x300.jpg 225w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/dibiesse1-135x180.jpg 135w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><\/div><a class=\"w-gallery-item-link\" aria-label=\"Dettaglio di una cucina su cui poggia un piano in acciaio dove si affiancano un lavello a vasca circolare e un piano cottura a gas su cui poggia una pentola. \nDietro al piano in acciaio si notano una cappa aspirante montata a muro e una paretina con scaffali con gocciolatoio \" href=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/dibiesse1.jpg\"><\/a><\/div><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/dibiesse2.jpg\" class=\"attachment-large size-large\" alt=\"Vista aerea di un&#039;isola affiancata da un tavolo circolare con sedie, sui cui \u00e8 montato un piano in acciaio sul quale si affiancano un lavello a vasca quadra e un piano cottura a gas a quattro fuochi. \nDi fronte al piano in acciaio \u00e8 montato un canale attrezzato sul quale poggiano svariati oggetti\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/dibiesse2.jpg 800w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/dibiesse2-300x225.jpg 300w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/dibiesse2-180x135.jpg 180w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/div><a class=\"w-gallery-item-link\" aria-label=\"Vista aerea di un&#039;isola affiancata da un tavolo circolare con sedie, sui cui \u00e8 montato un piano in acciaio sul quale si affiancano un lavello a vasca quadra e un piano cottura a gas a quattro fuochi. \nDi fronte al piano in acciaio \u00e8 montato un canale attrezzato sul quale poggiano svariati oggetti\" href=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/dibiesse2.jpg\"><\/a><\/div><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"408\" height=\"600\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/dibiesse3.jpg\" class=\"attachment-large size-large\" alt=\"Dettaglio di un piano cottura a gas in acciaio con griglie in ghisa su cui poggia una pentola\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/dibiesse3.jpg 408w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/dibiesse3-204x300.jpg 204w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/dibiesse3-122x180.jpg 122w\" sizes=\"auto, (max-width: 408px) 100vw, 408px\" \/><\/div><a class=\"w-gallery-item-link\" aria-label=\"Dettaglio di un piano cottura a gas in acciaio con griglie in ghisa su cui poggia una pentola \" href=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/dibiesse3.jpg\"><\/a><\/div><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"467\" height=\"600\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/mittel1.jpg\" class=\"attachment-large size-large\" alt=\"Vista di una zona living\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/mittel1.jpg 467w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/mittel1-234x300.jpg 234w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/mittel1-140x180.jpg 140w\" sizes=\"auto, (max-width: 467px) 100vw, 467px\" \/><\/div><a class=\"w-gallery-item-link\" aria-label=\"Vista di una zona living \" href=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/mittel1.jpg\"><\/a><\/div><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/mittel2.jpg\" class=\"attachment-large size-large\" alt=\"Vista di una zona living sul cui sfondo si vede una parete attrezzata e delle scaffalature e in primo piano un piano cottura a gas con tre fuochi\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/mittel2.jpg 800w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/mittel2-300x225.jpg 300w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/mittel2-180x135.jpg 180w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/div><a class=\"w-gallery-item-link\" aria-label=\"Vista di una zona living sul cui sfondo si vede una parete attrezzata e delle scaffalature e in primo piano un piano cottura a gas con tre fuochi \" href=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/mittel2.jpg\"><\/a><\/div><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/mittel3.jpg\" class=\"attachment-large size-large\" alt=\"Vista di una zona living al cui centro figura un piano da cucina incurvato su cui si affiancano piani cottura a gas e un lavello a due vasche. \nSullo sfondo si vedono una parete attrezzata e del mobilio verticale, di fianco al piano cucina ci sono due sedie\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/mittel3.jpg 800w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/mittel3-300x225.jpg 300w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/mittel3-180x135.jpg 180w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/div><a class=\"w-gallery-item-link\" aria-label=\"Vista di una zona living al cui centro figura un piano da cucina incurvato su cui si affiancano piani cottura a gas e un lavello a due vasche. \nSullo sfondo si vedono una parete attrezzata e del mobilio verticale, di fianco al piano cucina ci sono due sedie \" href=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/mittel3.jpg\"><\/a><\/div><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/mittel4.jpg\" class=\"attachment-large size-large\" alt=\"Vista frontale di una cucina, bianca e nera, contenente un piano su cui si affiancano lavello, piano cottura a gas e un forno incassato nel mobile verticale di destra.\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/mittel4.jpg 800w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/mittel4-300x225.jpg 300w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/mittel4-180x135.jpg 180w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/div><a class=\"w-gallery-item-link\" aria-label=\"Vista frontale di una cucina, bianca e nera, contenente un piano su cui si affiancano lavello, piano cottura a gas e un forno incassato nel mobile verticale di destra.\n\" href=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/mittel4.jpg\"><\/a><\/div><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/pedini1.jpg\" class=\"attachment-large size-large\" alt=\"Vista aerea di un piano da cucina su cui ci sono, ai due capi opposti, un lavello in acciaio a due vasche una circolare e una quadra e un piano cottura diviso a zone di forme diverse, una circolare e una quadra\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/pedini1.jpg 800w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/pedini1-300x225.jpg 300w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/pedini1-180x135.jpg 180w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/div><a class=\"w-gallery-item-link\" aria-label=\"Vista aerea di un piano da cucina su cui ci sono, ai due capi opposti, un lavello in acciaio a due vasche una circolare e una quadra e un piano cottura diviso a zone di forme diverse, una circolare e una quadra \" href=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/pedini1.jpg\"><\/a><\/div><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/pedini2.jpg\" class=\"attachment-large size-large\" alt=\"Dettaglio di un piano da cucina che mostra un wok in ghisa contenente del riso che poggia su un piano cottura in acciaio diviso in due fuochi dalle forme geometriche diverse\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/pedini2.jpg 800w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/pedini2-300x225.jpg 300w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/pedini2-180x135.jpg 180w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/div><a class=\"w-gallery-item-link\" aria-label=\"Dettaglio di un piano da cucina che mostra un wok in ghisa contenente del riso che poggia su un piano cottura in acciaio diviso in due fuochi dalle forme geometriche diverse\" href=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/pedini2.jpg\"><\/a><\/div><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/pedini3.jpg\" class=\"attachment-large size-large\" alt=\"Vista aerea di una zona living il cui punto focale \u00e8 un piano in legno su cui poggiano, ai capi opposti, due piani cottura e un lavello a due vasche.\nIntegrato al piano c&#039;\u00e8 un tavolo, affiancato da due sedie, su cui poggiano stoviglie varie\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/pedini3.jpg 800w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/pedini3-300x225.jpg 300w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/pedini3-180x135.jpg 180w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/div><a class=\"w-gallery-item-link\" aria-label=\"Vista aerea di una zona living il cui punto focale \u00e8 un piano in legno su cui poggiano, ai capi opposti, due piani cottura e un lavello a due vasche.\nIntegrato al piano c&#039;\u00e8 un tavolo, affiancato da due sedie, su cui poggiano stoviglie varie\" href=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/pedini3.jpg\"><\/a><\/div><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/pedini4.jpg\" class=\"attachment-large size-large\" alt=\"Vista aerea di un piano da cucina in legno che presenta due lavelli a vasca circolare in acciaio, uno a destra e uno a sinistra, in mezzo ai quali si trova un piano cottura a gas con cappa integrata\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/pedini4.jpg 800w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/pedini4-300x225.jpg 300w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/pedini4-180x135.jpg 180w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/div><a class=\"w-gallery-item-link\" aria-label=\"Vista aerea di un piano da cucina in legno che presenta due lavelli a vasca circolare in acciaio, uno a destra e uno a sinistra, in mezzo ai quali si trova un piano cottura a gas con cappa integrata \" href=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/pedini4.jpg\"><\/a><\/div><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"600\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/pedini5.jpg\" class=\"attachment-large size-large\" alt=\"Dettaglio di un piano di cucina che mostra un piano cottura a gas in acciaio con cappa integrata e un lavello a vasca circolare a fianco del quale sono poggiati dei vasi\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/pedini5.jpg 800w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/pedini5-300x225.jpg 300w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/pedini5-180x135.jpg 180w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/div><a class=\"w-gallery-item-link\" aria-label=\"Dettaglio di un piano di cucina che mostra un piano cottura a gas in acciaio con cappa integrata e un lavello a vasca circolare a fianco del quale sono poggiati dei vasi \" href=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/pedini5.jpg\"><\/a><\/div><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"658\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/pedini6.jpg\" class=\"attachment-large size-large\" alt=\"Vista di una zona living nella quale spicca una cucina composta da un piano che si sviluppa in una curva sulla quale poggiano un piano cottura e un lavello a due vasche. \nSullo sfondo ci sono delle finestre e altri oggetti di arredo\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/pedini6.jpg 900w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/pedini6-300x219.jpg 300w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/pedini6-180x132.jpg 180w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/div><a class=\"w-gallery-item-link\" aria-label=\"Vista di una zona living nella quale spicca una cucina composta da un piano che si sviluppa in una curva sulla quale poggiano un piano cottura e un lavello a due vasche. \nSullo sfondo ci sono delle finestre e altri oggetti di arredo\" href=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/pedini6.jpg\"><\/a><\/div><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"667\" height=\"1000\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/zampieri1.jpg\" class=\"attachment-large size-large\" alt=\"Dettaglio di un piano di lavoro che mostra un piano cottura in acciaio inox a 5 fuochi con griglie in ghisa e un lavello in acciaio inox su cui sono poggiati dei pomodori\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/zampieri1.jpg 667w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/zampieri1-200x300.jpg 200w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/zampieri1-120x180.jpg 120w\" sizes=\"auto, (max-width: 667px) 100vw, 667px\" \/><\/div><a class=\"w-gallery-item-link\" aria-label=\"Dettaglio di un piano di lavoro che mostra un piano cottura in acciaio inox a 5 fuochi con griglie in ghisa e un lavello in acciaio inox su cui sono poggiati dei pomodori \" href=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/zampieri1.jpg\"><\/a><\/div><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"857\" height=\"1000\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/zampieri2.jpg\" class=\"attachment-large size-large\" alt=\"Dettaglio di una cucina grigio perla satinato che comprende un piano di lavoro con lavello e piano di cottura a gas, due forni e altro mobilio\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/zampieri2.jpg 857w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/zampieri2-257x300.jpg 257w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/zampieri2-154x180.jpg 154w\" sizes=\"auto, (max-width: 857px) 100vw, 857px\" \/><\/div><a class=\"w-gallery-item-link\" aria-label=\"Dettaglio di una cucina grigio perla satinato che comprende un piano di lavoro con lavello e piano di cottura a gas, due forni e altro mobilio \" href=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/zampieri2.jpg\"><\/a><\/div><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"857\" height=\"1000\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/zampieri3.jpg\" class=\"attachment-large size-large\" alt=\"Vista frontale di una cucina grigio perla satinato composta da due piani di lavoro, scaffalature e stipetti sospesi\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/zampieri3.jpg 857w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/zampieri3-257x300.jpg 257w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/zampieri3-154x180.jpg 154w\" sizes=\"auto, (max-width: 857px) 100vw, 857px\" \/><\/div><a class=\"w-gallery-item-link\" aria-label=\"Vista frontale di una cucina grigio perla satinato composta da due piani di lavoro, scaffalature e stipetti sospesi \" href=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/zampieri3.jpg\"><\/a><\/div><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"650\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/zampieri4.jpg\" class=\"attachment-large size-large\" alt=\"Vista aerea di una cucina composta da due piani, di cui quello di sinistra occupato da un piano cottura a gas a cinque fuochi e un lavello a una vasca con gocciolatoio. Il mobile figura un cassetto aperto contenente dei piatti.\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/zampieri4.jpg 1000w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/zampieri4-300x195.jpg 300w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/zampieri4-180x117.jpg 180w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/div><a class=\"w-gallery-item-link\" aria-label=\"Vista aerea di una cucina composta da due piani, di cui quello di sinistra occupato da un piano cottura a gas a cinque fuochi e un lavello a una vasca con gocciolatoio. Il mobile figura un cassetto aperto contenente dei piatti. \n\" href=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/zampieri4.jpg\"><\/a><\/div><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"644\" height=\"387\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/composit1.png\" class=\"attachment-large size-large\" alt=\"Cucina a parete composta da un piano in acciaio con lavello e piano cottura, sormontato da una cappa aspirante, e del mobilio in legno scuro nel quale \u00e8 incassato un forno e sul quale poggiano degli oggetti decorativi\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/composit1.png 644w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/composit1-300x180.png 300w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/composit1-180x108.png 180w\" sizes=\"auto, (max-width: 644px) 100vw, 644px\" \/><\/div><a class=\"w-gallery-item-link\" aria-label=\"Cucina a parete composta da un piano in acciaio con lavello e piano cottura, sormontato da una cappa aspirante, e del mobilio in legno scuro nel quale \u00e8 incassato un forno e sul quale poggiano degli oggetti decorativi \" href=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/composit1.png\"><\/a><\/div><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"386\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/composit2.png\" class=\"attachment-large size-large\" alt=\"Dettaglio di una cucina con piano in acciaio sul quale si affiancano un piano cottura a gas a cinque fuochi e un lavello a vasca quadra.\nDi fianco al lavello c&#039;\u00e8 un forno incassato nel mobilio verticale\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/composit2.png 645w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/composit2-300x180.png 300w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/composit2-180x108.png 180w\" sizes=\"auto, (max-width: 645px) 100vw, 645px\" \/><\/div><a class=\"w-gallery-item-link\" aria-label=\"Dettaglio di una cucina con piano in acciaio sul quale si affiancano un piano cottura a gas a cinque fuochi e un lavello a vasca quadra.\nDi fianco al lavello c&#039;\u00e8 un forno incassato nel mobilio verticale \" href=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/composit2.png\"><\/a><\/div><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"371\" height=\"386\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/composit3.png\" class=\"attachment-large size-large\" alt=\"Cucina a parete dove figura un piano in acciaio montato su degli armadietti sul quale ci sono due lavelli a vasca quadra, posti a destra e a sinistra, in mezzo ai quali poggia un piano cottura a gas. \nIl piano \u00e8 sormontato da una cappa aspirante\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/composit3.png 371w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/composit3-288x300.png 288w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/composit3-173x180.png 173w\" sizes=\"auto, (max-width: 371px) 100vw, 371px\" \/><\/div><a class=\"w-gallery-item-link\" aria-label=\"Cucina a parete dove figura un piano in acciaio montato su degli armadietti sul quale ci sono due lavelli a vasca quadra, posti a destra e a sinistra, in mezzo ai quali poggia un piano cottura a gas. \nIl piano \u00e8 sormontato da una cappa aspirante \" href=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/composit3.png\"><\/a><\/div><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"646\" height=\"387\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/composit4.png\" class=\"attachment-large size-large\" alt=\"Vista di una cucina sul cui sfondo figurano dei forni incassati in una parete attrezzata con stipetti e scaffalature e, in primo piano, un&#039;isola in acciaio, sormontata da una cappa aspirante, su cui poggiano un piano cottura a gas, un lavello e degli oggetti decorativi\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/composit4.png 646w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/composit4-300x180.png 300w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/composit4-180x108.png 180w\" sizes=\"auto, (max-width: 646px) 100vw, 646px\" \/><\/div><a class=\"w-gallery-item-link\" aria-label=\"Vista di una cucina sul cui sfondo figurano dei forni incassati in una parete attrezzata con stipetti e scaffalature e, in primo piano, un&#039;isola in acciaio, sormontata da una cappa aspirante, su cui poggiano un piano cottura a gas, un lavello e degli oggetti decorativi \" href=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/composit4.png\"><\/a><\/div><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"385\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/GeD1.png\" class=\"attachment-large size-large\" alt=\"Vista di una cucina in legno composta da due piani montati su armadietti, sui quali sono poggiate delle stoviglie, che sorreggono un piano in acciaio sul quale \u00e8 incassato un lavello a vasca quadra.\nSu uno dei piani \u00e8 montato un piano a induzione sormontato da una cappa aspirante\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/GeD1.png 645w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/GeD1-300x179.png 300w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/GeD1-180x107.png 180w\" sizes=\"auto, (max-width: 645px) 100vw, 645px\" \/><\/div><a class=\"w-gallery-item-link\" aria-label=\"Vista di una cucina in legno composta da due piani montati su armadietti, sui quali sono poggiate delle stoviglie, che sorreggono un piano in acciaio sul quale \u00e8 incassato un lavello a vasca quadra.\nSu uno dei piani \u00e8 montato un piano a induzione sormontato da una cappa aspirante\" href=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/GeD1.png\"><\/a><\/div><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"321\" height=\"386\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/GeD2.png\" class=\"attachment-large size-large\" alt=\"Dettaglio di una cucina angolare in legno nella quale figura un piano in acciaio con lavello con rubinetto a doccia, a fianco al quale sono poggiati dei bicchieri e piatti\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/GeD2.png 321w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/GeD2-249x300.png 249w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/GeD2-150x180.png 150w\" sizes=\"auto, (max-width: 321px) 100vw, 321px\" \/><\/div><a class=\"w-gallery-item-link\" aria-label=\"Dettaglio di una cucina angolare in legno nella quale figura un piano in acciaio con lavello con rubinetto a doccia, a fianco al quale sono poggiati dei bicchieri e piatti\" href=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/GeD2.png\"><\/a><\/div><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"642\" height=\"384\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/GeD3.png\" class=\"attachment-large size-large\" alt=\"Dettaglio di una cucina angolare in legno nella quale figurano un piano in acciaio con lavello con rubinetto a doccia, a fianco al quale sono poggiati dei bicchieri, e un piano a induzione posto sotto una cappa aspirante\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/GeD3.png 642w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/GeD3-300x179.png 300w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/GeD3-180x108.png 180w\" sizes=\"auto, (max-width: 642px) 100vw, 642px\" \/><\/div><a class=\"w-gallery-item-link\" aria-label=\"Dettaglio di una cucina angolare in legno nella quale figurano un piano in acciaio con lavello con rubinetto a doccia, a fianco al quale sono poggiati dei bicchieri, e un piano a induzione posto sotto una cappa aspirante \" href=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/GeD3.png\"><\/a><\/div><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"357\" height=\"383\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/GeD4.png\" class=\"attachment-large size-large\" alt=\"Vista frontale di una cucina sul cui sfondo figura un piano in acciaio su cui poggia un lavello con rubinetto a doccia\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/GeD4.png 357w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/GeD4-280x300.png 280w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/GeD4-168x180.png 168w\" sizes=\"auto, (max-width: 357px) 100vw, 357px\" \/><\/div><a class=\"w-gallery-item-link\" aria-label=\"Vista frontale di una cucina sul cui sfondo figura un piano in acciaio su cui poggia un lavello con rubinetto a doccia \" href=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/GeD4.png\"><\/a><\/div><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"386\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/GeD5.png\" class=\"attachment-large size-large\" alt=\"Vista aerea di un piano in acciaio su cui poggiano un lavello con lavandino a doccia e una vasca e mezza, dei bicchieri a delle ciotole\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/GeD5.png 645w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/GeD5-300x180.png 300w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/GeD5-180x108.png 180w\" sizes=\"auto, (max-width: 645px) 100vw, 645px\" \/><\/div><a class=\"w-gallery-item-link\" aria-label=\"Vista aerea di un piano in acciaio su cui poggiano un lavello con lavandino a doccia e una vasca e mezza, dei bicchieri a delle ciotole \" href=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/GeD5.png\"><\/a><\/div><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"644\" height=\"385\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/lube1.png\" class=\"attachment-large size-large\" alt=\"Vista di una cucina sul cui sfondo figurano due forni circondati da stipetti e in, primo piano, un&#039;isola in acciaio su cui poggiano un piano cottura e un lavello e sotto la quale sono riposte delle pentole e ciotole\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/lube1.png 644w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/lube1-300x179.png 300w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/lube1-180x108.png 180w\" sizes=\"auto, (max-width: 644px) 100vw, 644px\" \/><\/div><a class=\"w-gallery-item-link\" aria-label=\"Vista di una cucina sul cui sfondo figurano due forni circondati da stipetti e in, primo piano, un&#039;isola in acciaio su cui poggiano un piano cottura e un lavello e sotto la quale sono riposte delle pentole e ciotole \" href=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/lube1.png\"><\/a><\/div><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"339\" height=\"385\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/lube4.png\" class=\"attachment-large size-large\" alt=\"Vista frontale di una cucina che presenta, sullo sfondo, dei forni circondati da\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/lube4.png 339w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/lube4-264x300.png 264w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/lube4-158x180.png 158w\" sizes=\"auto, (max-width: 339px) 100vw, 339px\" \/><\/div><a class=\"w-gallery-item-link\" aria-label=\"Vista frontale di una cucina che presenta, sullo sfondo, dei forni circondati da \" href=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/lube4.png\"><\/a><\/div><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"539\" height=\"385\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/mobillegno1.png\" class=\"attachment-large size-large\" alt=\"Dettaglio di un piano di cucina su cui poggiano, affiancati,\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/mobillegno1.png 539w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/mobillegno1-300x214.png 300w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/mobillegno1-180x129.png 180w\" sizes=\"auto, (max-width: 539px) 100vw, 539px\" \/><\/div><a class=\"w-gallery-item-link\" aria-label=\"Dettaglio di un piano di cucina su cui poggiano, affiancati, \" href=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/mobillegno1.png\"><\/a><\/div><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"646\" height=\"386\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/mobillegno3.png\" class=\"attachment-large size-large\" alt=\"Dettaglio di una cucina che mostra un piano cottura a gas, a cinque fuochi, con sopra delle pentole e affiancato da vari oggetti di decoro. \nSopra il piano di cottura figurano due stipetti bianchi\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/mobillegno3.png 646w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/mobillegno3-300x179.png 300w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/mobillegno3-180x108.png 180w\" sizes=\"auto, (max-width: 646px) 100vw, 646px\" \/><\/div><a class=\"w-gallery-item-link\" aria-label=\"Dettaglio di una cucina che mostra un piano cottura a gas, a cinque fuochi, con sopra delle pentole e affiancato da vari oggetti di decoro. \nSopra il piano di cottura figurano due stipetti bianchi \" href=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/mobillegno3.png\"><\/a><\/div><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"418\" height=\"386\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/modulnova3.png\" class=\"attachment-large size-large\" alt=\"Dettaglio di un piano da cucina su cui poggia un piano cottura a gas, affiancato da un utensile, con sopra una pentola\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/modulnova3.png 418w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/modulnova3-300x277.png 300w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/modulnova3-180x166.png 180w\" sizes=\"auto, (max-width: 418px) 100vw, 418px\" \/><\/div><a class=\"w-gallery-item-link\" aria-label=\"Dettaglio di un piano da cucina su cui poggia un piano cottura a gas, affiancato da un utensile, con sopra una pentola \" href=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/modulnova3.png\"><\/a><\/div><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"383\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/modulnova4.png\" class=\"attachment-large size-large\" alt=\"Vista di una cucina composta da due piani, posti parallelamente uno di fronte all&#039;altro, su cui rispettivamente poggiano un piano cottura e un lavello affiancato da stoviglie\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/modulnova4.png 645w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/modulnova4-300x178.png 300w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/modulnova4-180x107.png 180w\" sizes=\"auto, (max-width: 645px) 100vw, 645px\" \/><\/div><a class=\"w-gallery-item-link\" aria-label=\"Vista di una cucina composta da due piani, posti parallelamente uno di fronte all&#039;altro, su cui rispettivamente poggiano un piano cottura e un lavello affiancato da stoviglie\" href=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/modulnova4.png\"><\/a><\/div><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"644\" height=\"383\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/modulnova5.png\" class=\"attachment-large size-large\" alt=\"Vista di una cucina composta da due piani, posti parallelamente uno di fronte all&#039;altro, su cui rispettivamente poggiano un piano cottura e un lavello circondato da stoviglie\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/modulnova5.png 644w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/modulnova5-300x178.png 300w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/modulnova5-180x107.png 180w\" sizes=\"auto, (max-width: 644px) 100vw, 644px\" \/><\/div><a class=\"w-gallery-item-link\" aria-label=\"Vista di una cucina composta da due piani, posti parallelamente uno di fronte all&#039;altro, su cui rispettivamente poggiano un piano cottura e un lavello circondato da stoviglie\" href=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/modulnova5.png\"><\/a><\/div><div class=\"w-gallery-item\"><div class=\"w-gallery-item-img\"><img loading=\"lazy\" decoding=\"async\" width=\"645\" height=\"387\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/valdesign2.png\" class=\"attachment-large size-large\" alt=\"Vista di una cucina composta da un piano arancione e uno bianco che supportano un piano cottura in acciaio. \nIn primo piano ci sono degli sgabelli posti di fronte al piano arancione e sullo sfondo delle scaffalature contenenti dei bicchieri\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/valdesign2.png 645w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/valdesign2-300x180.png 300w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/valdesign2-180x108.png 180w\" sizes=\"auto, (max-width: 645px) 100vw, 645px\" \/><\/div><a class=\"w-gallery-item-link\" aria-label=\"Vista di una cucina composta da un piano arancione e uno bianco che supportano un piano cottura in acciaio. \nIn primo piano ci sono degli sgabelli posti di fronte al piano arancione e sullo sfondo delle scaffalature contenenti dei bicchieri \" href=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/valdesign2.png\"><\/a><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section>\n","protected":false},"excerpt":{"rendered":"[vc_custom_heading text=\"INDIVIDUELLE L\u00d6SUNGEN F\u00dcR ELEGANTE UND STILVOLLE K\u00dcCHEN\" font_container=\"tag:h1|text_align:left\"]Die folgenden Fotosammlungen zeigen Beispiele f\u00fcr Sonderanfertigungen, die von Barazza realisiert wurden: dank der fruchtbaren Zusammenarbeit mit Architekten, Planern und M\u00f6belfirmen konnten einzigartige, individuelle und perfekt auf die Bed\u00fcrfnisse des Auftraggebers abgestimmte Einrichtungsl\u00f6sungen kreiert werden. Die Vielseitigkeit von Edelstahl, die klaren Linien und die edlen Details erm\u00f6glichen...","protected":false},"author":1,"featured_media":100572,"parent":109081,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-109264","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Galerie - Barazza srl<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/barazzasrl.it\/de\/fuoriserie\/galerie\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Galerie - Barazza srl\" \/>\n<meta property=\"og:url\" content=\"https:\/\/barazzasrl.it\/de\/fuoriserie\/galerie\/\" \/>\n<meta property=\"og:site_name\" content=\"Barazza srl\" \/>\n<meta property=\"article:modified_time\" content=\"2025-11-06T15:45:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_fuoriserie-banner_references.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"474\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data1\" content=\"1\u00a0Minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/barazzasrl.it\/de\/fuoriserie\/galerie\/\",\"url\":\"https:\/\/barazzasrl.it\/de\/fuoriserie\/galerie\/\",\"name\":\"Galerie - Barazza srl\",\"isPartOf\":{\"@id\":\"https:\/\/barazzasrl.it\/fr\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/barazzasrl.it\/de\/fuoriserie\/galerie\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/barazzasrl.it\/de\/fuoriserie\/galerie\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_fuoriserie-banner_references.jpg\",\"datePublished\":\"2025-08-21T12:17:18+00:00\",\"dateModified\":\"2025-11-06T15:45:44+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/barazzasrl.it\/de\/fuoriserie\/galerie\/#breadcrumb\"},\"inLanguage\":\"de\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/barazzasrl.it\/de\/fuoriserie\/galerie\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"de\",\"@id\":\"https:\/\/barazzasrl.it\/de\/fuoriserie\/galerie\/#primaryimage\",\"url\":\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_fuoriserie-banner_references.jpg\",\"contentUrl\":\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_fuoriserie-banner_references.jpg\",\"width\":1920,\"height\":474,\"caption\":\"Vista dal basso di una cupola a vetri.\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/barazzasrl.it\/de\/fuoriserie\/galerie\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/barazzasrl.it\/de\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Sonderausf\u00fchrungen\",\"item\":\"https:\/\/barazzasrl.it\/de\/fuoriserie\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Galerie\",\"item\":\"https:\/\/barazzasrl.it\/de\/fuoriserie\/galerie\/\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/barazzasrl.it\/fr\/#website\",\"url\":\"https:\/\/barazzasrl.it\/fr\/\",\"name\":\"Barazza srl\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/barazzasrl.it\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Galerie - Barazza srl","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/barazzasrl.it\/de\/fuoriserie\/galerie\/","og_locale":"de_DE","og_type":"article","og_title":"Galerie - Barazza srl","og_url":"https:\/\/barazzasrl.it\/de\/fuoriserie\/galerie\/","og_site_name":"Barazza srl","article_modified_time":"2025-11-06T15:45:44+00:00","og_image":[{"width":1920,"height":474,"url":"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_fuoriserie-banner_references.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_misc":{"Gesch\u00e4tzte Lesezeit":"1\u00a0Minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/barazzasrl.it\/de\/fuoriserie\/galerie\/","url":"https:\/\/barazzasrl.it\/de\/fuoriserie\/galerie\/","name":"Galerie - Barazza srl","isPartOf":{"@id":"https:\/\/barazzasrl.it\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/barazzasrl.it\/de\/fuoriserie\/galerie\/#primaryimage"},"image":{"@id":"https:\/\/barazzasrl.it\/de\/fuoriserie\/galerie\/#primaryimage"},"thumbnailUrl":"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_fuoriserie-banner_references.jpg","datePublished":"2025-08-21T12:17:18+00:00","dateModified":"2025-11-06T15:45:44+00:00","breadcrumb":{"@id":"https:\/\/barazzasrl.it\/de\/fuoriserie\/galerie\/#breadcrumb"},"inLanguage":"de","potentialAction":[{"@type":"ReadAction","target":["https:\/\/barazzasrl.it\/de\/fuoriserie\/galerie\/"]}]},{"@type":"ImageObject","inLanguage":"de","@id":"https:\/\/barazzasrl.it\/de\/fuoriserie\/galerie\/#primaryimage","url":"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_fuoriserie-banner_references.jpg","contentUrl":"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_fuoriserie-banner_references.jpg","width":1920,"height":474,"caption":"Vista dal basso di una cupola a vetri."},{"@type":"BreadcrumbList","@id":"https:\/\/barazzasrl.it\/de\/fuoriserie\/galerie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/barazzasrl.it\/de\/"},{"@type":"ListItem","position":2,"name":"Sonderausf\u00fchrungen","item":"https:\/\/barazzasrl.it\/de\/fuoriserie\/"},{"@type":"ListItem","position":3,"name":"Galerie","item":"https:\/\/barazzasrl.it\/de\/fuoriserie\/galerie\/"}]},{"@type":"WebSite","@id":"https:\/\/barazzasrl.it\/fr\/#website","url":"https:\/\/barazzasrl.it\/fr\/","name":"Barazza srl","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/barazzasrl.it\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de"}]}},"_links":{"self":[{"href":"https:\/\/barazzasrl.it\/de\/wp-json\/wp\/v2\/pages\/109264","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/barazzasrl.it\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/barazzasrl.it\/de\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/barazzasrl.it\/de\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/barazzasrl.it\/de\/wp-json\/wp\/v2\/comments?post=109264"}],"version-history":[{"count":2,"href":"https:\/\/barazzasrl.it\/de\/wp-json\/wp\/v2\/pages\/109264\/revisions"}],"predecessor-version":[{"id":110020,"href":"https:\/\/barazzasrl.it\/de\/wp-json\/wp\/v2\/pages\/109264\/revisions\/110020"}],"up":[{"embeddable":true,"href":"https:\/\/barazzasrl.it\/de\/wp-json\/wp\/v2\/pages\/109081"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/barazzasrl.it\/de\/wp-json\/wp\/v2\/media\/100572"}],"wp:attachment":[{"href":"https:\/\/barazzasrl.it\/de\/wp-json\/wp\/v2\/media?parent=109264"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}