{"id":104835,"date":"2025-07-31T14:07:23","date_gmt":"2025-07-31T12:07:23","guid":{"rendered":"http:\/\/barazzasrl.it\/mood\/"},"modified":"2025-12-12T11:30:55","modified_gmt":"2025-12-12T10:30:55","slug":"mood","status":"publish","type":"page","link":"https:\/\/barazzasrl.it\/en\/collections\/mood\/","title":{"rendered":"Mood"},"content":{"rendered":"<section class=\"l-section wpb_row height_auto\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n\t\t\t\t<p class=\"rs-p-wp-fix\"><\/p>\n\t\t\t\t<sr7-module data-alias=\"icon-it-11\" data-id=\"10\" id=\"SR7_10_1\" class=\"rs-ov-hidden\" data-version=\"6.7.38\">\n\t\t\t\t\t<sr7-adjuster><\/sr7-adjuster>\n\t\t\t\t\t<sr7-content>\n\t\t\t\t\t\t<sr7-slide id=\"SR7_10_1-34\" data-key=\"34\">\n\t\t\t\t\t\t<\/sr7-slide>\n\t\t\t\t\t\t<sr7-slide id=\"SR7_10_1-35\" data-key=\"35\">\n\t\t\t\t\t\t<\/sr7-slide>\n\t\t\t\t\t<\/sr7-content>\n\t\t\t\t<\/sr7-module>\n\t\t\t\t<script>\n\t\t\t\t\tSR7.PMH ??={}; SR7.PMH[\"SR7_10_1\"] = {cn:100,state:false,fn: function() { if (_tpt!==undefined && _tpt.prepareModuleHeight !== undefined) {  _tpt.prepareModuleHeight({id:\"SR7_10_1\",el:[945,945,945,560,720],type:'standard',shdw:'0',gh:[945,945,945,560,720],gw:[1680,1680,1680,778,480],vpt:['-100px&#039;,&#039;-100px&#039;,&#039;-100px&#039;,&#039;-100px&#039;,&#039;-100px'],size:{fullWidth:true, fullHeight:false},mh:'0',onh:0,onw:0,bg:{color:'{\"orig\":\"transparent\",\"type\":\"solid\",\"string\":\"transparent\"}'}});   SR7.PMH[\"SR7_10_1\"].state=true;} else if(SR7.PMH[\"SR7_10_1\"].cn-->0)\tsetTimeout( SR7.PMH[\"SR7_10_1\"].fn,19);}};SR7.PMH[\"SR7_10_1\" ].fn();\n\t\t\t\t<\/script>\n<\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_medium\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">[vc_empty_space]<\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_auto\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default reversed stacking_default\"><div class=\"vc_col-sm-2\/5 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">[vc_single_image image=&#8221;97052&#8243; img_size=&#8221;full&#8221; css=&#8221;&#8221;][vc_empty_space]<\/div><\/div><\/div><div class=\"vc_col-sm-3\/5 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">[vc_custom_heading text=&#8221;<em>MOOD<\/em><br \/>\nCOLLECTION&#8221; font_container=&#8221;tag:h1|text_align:left&#8221;][vc_empty_space]<\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_auto\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_bottom type_default stacking_default\"><div class=\"vc_col-sm-2\/5 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"w-grid type_grid layout_gallery_default cols_5 valign_center preload_style_spinner\" id=\"us_grid_1\" style=\"--columns:5;--gap:2px;\" data-filterable=\"true\"><style>.layout_gallery_default .w-grid-item-h{}<\/style><div class=\"w-grid-list\">\t<article class=\"w-grid-item size_1x1 post-94730 attachment type-attachment status-inherit hentry\" data-id=\"94730\">\r\n\t\t<div class=\"w-grid-item-h\">\r\n\t\t\t\t\t\t<div class=\"w-post-elm post_image usg_post_image_1 stretched\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/07\/Barazza_Gamme_Lavandini.svg\" class=\"attachment-large size-large\" alt=\"\" \/><\/div>\t\t<\/div>\r\n\t\t\t<\/article>\r\n\t<article class=\"w-grid-item size_1x1 post-94709 attachment type-attachment status-inherit hentry\" data-id=\"94709\">\r\n\t\t<div class=\"w-grid-item-h\">\r\n\t\t\t\t\t\t<div class=\"w-post-elm post_image usg_post_image_1 stretched\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/07\/Barazza_Gamme_Cappe.svg\" class=\"attachment-large size-large\" alt=\"\" \/><\/div>\t\t<\/div>\r\n\t\t\t<\/article>\r\n\t<article class=\"w-grid-item size_1x1 post-94695 attachment type-attachment status-inherit hentry\" data-id=\"94695\">\r\n\t\t<div class=\"w-grid-item-h\">\r\n\t\t\t\t\t\t<div class=\"w-post-elm post_image usg_post_image_1 stretched\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"1024\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/07\/Barazza_Gamme_Piani-cottura.svg\" class=\"attachment-large size-large\" alt=\"\" \/><\/div>\t\t<\/div>\r\n\t\t\t<\/article>\r\n<\/div><div class=\"w-grid-preloader\">\t<div class=\"g-preloader type_1\">\r\n\t\t<div><\/div>\r\n\t<\/div>\r\n\t<\/div>\t<div class=\"w-grid-json hidden\" onclick='return {&quot;action&quot;:&quot;us_ajax_grid&quot;,&quot;infinite_scroll&quot;:0,&quot;max_num_pages&quot;:1,&quot;pagination&quot;:&quot;none&quot;,&quot;template_vars&quot;:{&quot;columns&quot;:&quot;5&quot;,&quot;exclude_items&quot;:&quot;none&quot;,&quot;img_size&quot;:&quot;default&quot;,&quot;ignore_items_size&quot;:0,&quot;items_layout&quot;:&quot;gallery_default&quot;,&quot;items_offset&quot;:&quot;1&quot;,&quot;load_animation&quot;:&quot;none&quot;,&quot;overriding_link&quot;:&quot;%7B%22url%22%3A%22%22%7D&quot;,&quot;post_id&quot;:0,&quot;query_args&quot;:{&quot;post_type&quot;:[&quot;attachment&quot;],&quot;post__in&quot;:[&quot;94706&quot;,&quot;94692&quot;,&quot;94727&quot;],&quot;post_status&quot;:&quot;inherit&quot;,&quot;post_mime_type&quot;:&quot;image&quot;,&quot;posts_per_page&quot;:&quot;10&quot;},&quot;orderby_query_args&quot;:{&quot;orderby&quot;:{&quot;date&quot;:&quot;DESC&quot;}},&quot;type&quot;:&quot;grid&quot;,&quot;us_grid_post_type&quot;:&quot;attachment&quot;,&quot;us_grid_ajax_index&quot;:1,&quot;us_grid_filter_query_string&quot;:null,&quot;us_grid_index&quot;:1,&quot;page_args&quot;:[],&quot;lang&quot;:&quot;en&quot;}}'><\/div>\r\n\t<\/div><\/div><\/div><\/div><div class=\"vc_col-sm-3\/5 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p class=\"p1\">Full stainless steel 4 mm thick and the technology applied to a latest generation burner make this range, made up of hobs, cooker hoods, sinks and taps, a classic example of design and refinement. The option to choose between satin and Mat stainless steel, black and white glass finishes means the style can be adapted to your particular needs.<\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_medium\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">[vc_empty_space]<\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_auto width_full\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-10 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><div><div id=\"image-map-pro-2712730e-d89e-4aa2-8853-0e0acd4b1717\"><\/div><\/div>\n<\/div><\/div><\/div><\/div><\/div><div class=\"vc_col-sm-2 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_medium\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_auto\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h2>GALLERY<br \/>\n<em>MOOD <\/em>COLLECTION<\/h2>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_medium width_full\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n    <div class=\"brz-carousel \">\n        <div class=\"carousel-wrapper\">\n\n            <!-- MOBILE ARROWS -->\n            <div class=\"mobile-arrows\">\n                <button class=\"custom-prev icon-slider-sx color-black\"><\/button>\n                <button class=\"custom-next icon-slider-dx color-black\"><\/button>\n            <\/div>\n                        <!-- DESKTOP LEFT ARROW -->\n            <div class=\"arrow-zone left-arrow-zone\">\n                <button class=\"custom-prev icon-slider-sx color-black\"><\/button>\n            <\/div>\n                        <!-- CAROUSEL -->\n            <div class=\"carousel-container\">\n                <div class=\"carousel\">\n                                            <div class=\"carousel-item bg-grey color-white\">\n                            <div class=\"carousel-item-img\" data-img-src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_kitchen-scaled.jpg\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"1980\" height=\"863\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_kitchen-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_kitchen-scaled.jpg 1980w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_kitchen-300x131.jpg 300w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_kitchen-1024x446.jpg 1024w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_kitchen-180x78.jpg 180w\" sizes=\"auto, (max-width: 1980px) 100vw, 1980px\" \/>                            <\/div>\n                        <\/div>\n                    \n                                            <div class=\"carousel-item bg-grey color-white\">\n                            <div class=\"carousel-item-img\" data-img-src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_cooker-hood-scaled.jpg\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"1980\" height=\"864\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_cooker-hood-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_cooker-hood-scaled.jpg 1980w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_cooker-hood-300x131.jpg 300w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_cooker-hood-1024x447.jpg 1024w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_cooker-hood-180x79.jpg 180w\" sizes=\"auto, (max-width: 1980px) 100vw, 1980px\" \/>                            <\/div>\n                        <\/div>\n                    \n                                            <div class=\"carousel-item bg-grey color-white\">\n                            <div class=\"carousel-item-img\" data-img-src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_hob-gas-5-burners-scaled.jpg\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"1980\" height=\"864\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_hob-gas-5-burners-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_hob-gas-5-burners-scaled.jpg 1980w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_hob-gas-5-burners-300x131.jpg 300w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_hob-gas-5-burners-1024x447.jpg 1024w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_hob-gas-5-burners-180x79.jpg 180w\" sizes=\"auto, (max-width: 1980px) 100vw, 1980px\" \/>                            <\/div>\n                        <\/div>\n                    \n                                            <div class=\"carousel-item bg-grey color-white\">\n                            <div class=\"carousel-item-img\" data-img-src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_hob-gas-black-scaled.jpg\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"1980\" height=\"863\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_hob-gas-black-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_hob-gas-black-scaled.jpg 1980w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_hob-gas-black-300x131.jpg 300w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_hob-gas-black-1024x446.jpg 1024w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_hob-gas-black-180x78.jpg 180w\" sizes=\"auto, (max-width: 1980px) 100vw, 1980px\" \/>                            <\/div>\n                        <\/div>\n                    \n                                            <div class=\"carousel-item bg-grey color-white\">\n                            <div class=\"carousel-item-img\" data-img-src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_hob-gas-burner-scaled.jpg\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"1980\" height=\"863\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_hob-gas-burner-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_hob-gas-burner-scaled.jpg 1980w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_hob-gas-burner-300x131.jpg 300w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_hob-gas-burner-1024x446.jpg 1024w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_hob-gas-burner-180x78.jpg 180w\" sizes=\"auto, (max-width: 1980px) 100vw, 1980px\" \/>                            <\/div>\n                        <\/div>\n                    \n                                            <div class=\"carousel-item bg-grey color-white\">\n                            <div class=\"carousel-item-img\" data-img-src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_hob-gas-burner.jpg_detail-scaled.jpg\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"1980\" height=\"863\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_hob-gas-burner.jpg_detail-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_hob-gas-burner.jpg_detail-scaled.jpg 1980w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_hob-gas-burner.jpg_detail-300x131.jpg 300w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_hob-gas-burner.jpg_detail-1024x446.jpg 1024w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_hob-gas-burner.jpg_detail-180x78.jpg 180w\" sizes=\"auto, (max-width: 1980px) 100vw, 1980px\" \/>                            <\/div>\n                        <\/div>\n                    \n                                            <div class=\"carousel-item bg-grey color-white\">\n                            <div class=\"carousel-item-img\" data-img-src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_hob-gas-knobs.jpg\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"1800\" height=\"785\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_hob-gas-knobs.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_hob-gas-knobs.jpg 1800w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_hob-gas-knobs-300x131.jpg 300w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_hob-gas-knobs-1024x447.jpg 1024w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_hob-gas-knobs-180x79.jpg 180w\" sizes=\"auto, (max-width: 1800px) 100vw, 1800px\" \/>                            <\/div>\n                        <\/div>\n                    \n                                            <div class=\"carousel-item bg-grey color-white\">\n                            <div class=\"carousel-item-img\" data-img-src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_hob-gas-sink-scaled.jpg\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"1980\" height=\"864\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_hob-gas-sink-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_hob-gas-sink-scaled.jpg 1980w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_hob-gas-sink-300x131.jpg 300w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_hob-gas-sink-1024x447.jpg 1024w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_hob-gas-sink-180x79.jpg 180w\" sizes=\"auto, (max-width: 1980px) 100vw, 1980px\" \/>                            <\/div>\n                        <\/div>\n                    \n                                            <div class=\"carousel-item bg-grey color-white\">\n                            <div class=\"carousel-item-img\" data-img-src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_hob-gas-steel.jpg\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"1800\" height=\"785\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_hob-gas-steel.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_hob-gas-steel.jpg 1800w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_hob-gas-steel-300x131.jpg 300w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_hob-gas-steel-1024x447.jpg 1024w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_hob-gas-steel-180x79.jpg 180w\" sizes=\"auto, (max-width: 1800px) 100vw, 1800px\" \/>                            <\/div>\n                        <\/div>\n                    \n                                            <div class=\"carousel-item bg-grey color-white\">\n                            <div class=\"carousel-item-img\" data-img-src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_hob-gas-white-scaled.jpg\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"1980\" height=\"863\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_hob-gas-white-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_hob-gas-white-scaled.jpg 1980w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_hob-gas-white-300x131.jpg 300w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_hob-gas-white-1024x446.jpg 1024w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_hob-gas-white-180x78.jpg 180w\" sizes=\"auto, (max-width: 1980px) 100vw, 1980px\" \/>                            <\/div>\n                        <\/div>\n                    \n                                            <div class=\"carousel-item bg-grey color-white\">\n                            <div class=\"carousel-item-img\" data-img-src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_hob-gas_sink-steel-scaled.jpg\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"1980\" height=\"864\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_hob-gas_sink-steel-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_hob-gas_sink-steel-scaled.jpg 1980w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_hob-gas_sink-steel-300x131.jpg 300w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_hob-gas_sink-steel-1024x447.jpg 1024w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_hob-gas_sink-steel-180x79.jpg 180w\" sizes=\"auto, (max-width: 1980px) 100vw, 1980px\" \/>                            <\/div>\n                        <\/div>\n                    \n                                            <div class=\"carousel-item bg-grey color-white\">\n                            <div class=\"carousel-item-img\" data-img-src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_sink-accessories.jpg\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"1800\" height=\"786\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_sink-accessories.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_sink-accessories.jpg 1800w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_sink-accessories-300x131.jpg 300w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_sink-accessories-1024x447.jpg 1024w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_sink-accessories-180x79.jpg 180w\" sizes=\"auto, (max-width: 1800px) 100vw, 1800px\" \/>                            <\/div>\n                        <\/div>\n                    \n                                            <div class=\"carousel-item bg-grey color-white\">\n                            <div class=\"carousel-item-img\" data-img-src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_sink-accessories_detail-scaled.jpg\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"1980\" height=\"863\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_sink-accessories_detail-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_sink-accessories_detail-scaled.jpg 1980w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_sink-accessories_detail-300x131.jpg 300w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_sink-accessories_detail-1024x446.jpg 1024w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_sink-accessories_detail-180x78.jpg 180w\" sizes=\"auto, (max-width: 1980px) 100vw, 1980px\" \/>                            <\/div>\n                        <\/div>\n                    \n                                            <div class=\"carousel-item bg-grey color-white\">\n                            <div class=\"carousel-item-img\" data-img-src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_sink-bowl-scaled.jpg\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"1980\" height=\"863\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_sink-bowl-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_sink-bowl-scaled.jpg 1980w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_sink-bowl-300x131.jpg 300w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_sink-bowl-1024x446.jpg 1024w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_sink-bowl-180x78.jpg 180w\" sizes=\"auto, (max-width: 1980px) 100vw, 1980px\" \/>                            <\/div>\n                        <\/div>\n                    \n                                            <div class=\"carousel-item bg-grey color-white\">\n                            <div class=\"carousel-item-img\" data-img-src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_sink-finish-scaled.jpg\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"1980\" height=\"864\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_sink-finish-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_sink-finish-scaled.jpg 1980w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_sink-finish-300x131.jpg 300w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_sink-finish-1024x447.jpg 1024w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_sink-finish-180x79.jpg 180w\" sizes=\"auto, (max-width: 1980px) 100vw, 1980px\" \/>                            <\/div>\n                        <\/div>\n                    \n                                            <div class=\"carousel-item bg-grey color-white\">\n                            <div class=\"carousel-item-img\" data-img-src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_sink-scaled.jpg\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"1980\" height=\"863\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_sink-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_sink-scaled.jpg 1980w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_sink-300x131.jpg 300w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_sink-1024x446.jpg 1024w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_sink-180x78.jpg 180w\" sizes=\"auto, (max-width: 1980px) 100vw, 1980px\" \/>                            <\/div>\n                        <\/div>\n                    \n                                            <div class=\"carousel-item bg-grey color-white\">\n                            <div class=\"carousel-item-img\" data-img-src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_steel-taps-1.jpg\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"1800\" height=\"785\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_steel-taps-1.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_steel-taps-1.jpg 1800w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_steel-taps-1-300x131.jpg 300w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_steel-taps-1-1024x447.jpg 1024w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_steel-taps-1-180x79.jpg 180w\" sizes=\"auto, (max-width: 1800px) 100vw, 1800px\" \/>                            <\/div>\n                        <\/div>\n                    \n                                            <div class=\"carousel-item bg-grey color-white\">\n                            <div class=\"carousel-item-img\" data-img-src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_steel-taps-1_accessories-scaled.jpg\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"1980\" height=\"863\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_steel-taps-1_accessories-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_steel-taps-1_accessories-scaled.jpg 1980w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_steel-taps-1_accessories-300x131.jpg 300w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_steel-taps-1_accessories-1024x446.jpg 1024w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_steel-taps-1_accessories-180x78.jpg 180w\" sizes=\"auto, (max-width: 1980px) 100vw, 1980px\" \/>                            <\/div>\n                        <\/div>\n                    \n                                            <div class=\"carousel-item bg-grey color-white\">\n                            <div class=\"carousel-item-img\" data-img-src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_steel-taps-1_detail-scaled.jpg\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"1980\" height=\"863\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_steel-taps-1_detail-scaled.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_steel-taps-1_detail-scaled.jpg 1980w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_steel-taps-1_detail-300x131.jpg 300w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_steel-taps-1_detail-1024x446.jpg 1024w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_steel-taps-1_detail-180x78.jpg 180w\" sizes=\"auto, (max-width: 1980px) 100vw, 1980px\" \/>                            <\/div>\n                        <\/div>\n                    \n                                            <div class=\"carousel-item bg-grey color-white\">\n                            <div class=\"carousel-item-img\" data-img-src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_steel-taps-2.jpg\">\n                                <img loading=\"lazy\" decoding=\"async\" width=\"1800\" height=\"785\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_steel-taps-2.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_steel-taps-2.jpg 1800w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_steel-taps-2-300x131.jpg 300w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_steel-taps-2-1024x447.jpg 1024w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_collections_mood_steel-taps-2-180x79.jpg 180w\" sizes=\"auto, (max-width: 1800px) 100vw, 1800px\" \/>                            <\/div>\n                        <\/div>\n                    \n                                        <!-- Add carousel-item-->\n                <\/div>\n\n                <!-- NAVIGATION -->\n                <!-- (bds-nav-left-align \/ bds-nav-right-align) -->\n                <div class=\"bds-nav-dots-wrapper bds-nav-right-align\">\n                    <div class=\"bds-nav-dots\">\n                                                <div class=\"bds-nav-dot-item slider-navigation-bar-active\" data-index=\"0\">\n                            <div class=\"slider-navigation-bar color-black\"><\/div>\n                        <\/div>\n                                                <div class=\"bds-nav-dot-item \" data-index=\"1\">\n                            <div class=\"slider-navigation-bar color-black\"><\/div>\n                        <\/div>\n                                                <div class=\"bds-nav-dot-item \" data-index=\"2\">\n                            <div class=\"slider-navigation-bar color-black\"><\/div>\n                        <\/div>\n                                                <div class=\"bds-nav-dot-item \" data-index=\"3\">\n                            <div class=\"slider-navigation-bar color-black\"><\/div>\n                        <\/div>\n                                                <div class=\"bds-nav-dot-item \" data-index=\"4\">\n                            <div class=\"slider-navigation-bar color-black\"><\/div>\n                        <\/div>\n                                                <div class=\"bds-nav-dot-item \" data-index=\"5\">\n                            <div class=\"slider-navigation-bar color-black\"><\/div>\n                        <\/div>\n                                                <div class=\"bds-nav-dot-item \" data-index=\"6\">\n                            <div class=\"slider-navigation-bar color-black\"><\/div>\n                        <\/div>\n                                                <div class=\"bds-nav-dot-item \" data-index=\"7\">\n                            <div class=\"slider-navigation-bar color-black\"><\/div>\n                        <\/div>\n                                                <div class=\"bds-nav-dot-item \" data-index=\"8\">\n                            <div class=\"slider-navigation-bar color-black\"><\/div>\n                        <\/div>\n                                                <div class=\"bds-nav-dot-item \" data-index=\"9\">\n                            <div class=\"slider-navigation-bar color-black\"><\/div>\n                        <\/div>\n                                                <div class=\"bds-nav-dot-item \" data-index=\"10\">\n                            <div class=\"slider-navigation-bar color-black\"><\/div>\n                        <\/div>\n                                                <div class=\"bds-nav-dot-item \" data-index=\"11\">\n                            <div class=\"slider-navigation-bar color-black\"><\/div>\n                        <\/div>\n                                                <div class=\"bds-nav-dot-item \" data-index=\"12\">\n                            <div class=\"slider-navigation-bar color-black\"><\/div>\n                        <\/div>\n                                                <div class=\"bds-nav-dot-item \" data-index=\"13\">\n                            <div class=\"slider-navigation-bar color-black\"><\/div>\n                        <\/div>\n                                                <div class=\"bds-nav-dot-item \" data-index=\"14\">\n                            <div class=\"slider-navigation-bar color-black\"><\/div>\n                        <\/div>\n                                                <div class=\"bds-nav-dot-item \" data-index=\"15\">\n                            <div class=\"slider-navigation-bar color-black\"><\/div>\n                        <\/div>\n                                                <div class=\"bds-nav-dot-item \" data-index=\"16\">\n                            <div class=\"slider-navigation-bar color-black\"><\/div>\n                        <\/div>\n                                                <div class=\"bds-nav-dot-item \" data-index=\"17\">\n                            <div class=\"slider-navigation-bar color-black\"><\/div>\n                        <\/div>\n                                                <div class=\"bds-nav-dot-item \" data-index=\"18\">\n                            <div class=\"slider-navigation-bar color-black\"><\/div>\n                        <\/div>\n                                                <div class=\"bds-nav-dot-item \" data-index=\"19\">\n                            <div class=\"slider-navigation-bar color-black\"><\/div>\n                        <\/div>\n                                                <!-- Add navigation item -->\n                    <\/div>\n                <\/div>\n\n            <\/div>\n                    <\/div>\n\n    <\/div>\n\n<\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_medium\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_medium\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><h2>FEATURES OF THE<br \/>\n<em>MOOD <\/em>COLLECTION<\/h2>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_auto width_full\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n    <section class=\"scroll-image \">\n\n        <div class=\"sticky\">\n            <div class=\"blocks-parent position-relative\">\n\n                <div class=\"block-item left \">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"1165\" height=\"1040\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_Mood_fornelli_scorrevole1.jpg\" class=\"block-item-bg\" alt=\"Dettaglio di un piano di cottura a gas in acciaio inox nel quale figurano delle manopole nere e delle griglie in ghisa.\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_Mood_fornelli_scorrevole1.jpg 1165w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_Mood_fornelli_scorrevole1-300x268.jpg 300w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_Mood_fornelli_scorrevole1-1024x914.jpg 1024w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_Mood_fornelli_scorrevole1-180x161.jpg 180w\" sizes=\"auto, (max-width: 1165px) 100vw, 1165px\" \/>                    \n                    <div class=\"flex-center\">\n                        <div class=\"block-item-content color-white\">\n                            \n                            \n                                                    <\/div>\n                    <\/div>\n                    \n                <\/div>\n\n                <div class=\"block-item action-scroll \">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"1074\" height=\"959\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_Mood_fornelli_scorrevole2.jpg\" class=\"block-item-bg\" alt=\"Dettaglio di un piano da cucina sul quale si affiancano un lavello a due vasche bianco e un piano di cottura a gas in vetroceramica bianca. Sul piano da cucina ci sono degli accessori.\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_Mood_fornelli_scorrevole2.jpg 1074w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_Mood_fornelli_scorrevole2-300x268.jpg 300w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_Mood_fornelli_scorrevole2-1024x914.jpg 1024w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_Mood_fornelli_scorrevole2-180x161.jpg 180w\" sizes=\"auto, (max-width: 1074px) 100vw, 1074px\" \/>                    \n                    <div class=\"flex-center\">\n                        <div class=\"block-item-content color-white\">\n                            \n                            \n                                                    <\/div>\n                    <\/div>\n                    \n                <\/div>\n\n                <div class=\"block-item right \">\n                    <img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"893\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/12\/Barazza_Mood_steel_sink_scorrevole3.jpg\" class=\"block-item-bg\" alt=\"\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/12\/Barazza_Mood_steel_sink_scorrevole3.jpg 1000w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/12\/Barazza_Mood_steel_sink_scorrevole3-300x268.jpg 300w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/12\/Barazza_Mood_steel_sink_scorrevole3-180x161.jpg 180w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>\n                    <div class=\"flex-center\">\n                        <div class=\"block-item-content color-white\">\n                            \n                            \n                                                    <\/div>\n                    <\/div>\n\n                <\/div>\n\n            <\/div>\n        <\/div>\n\n    <\/section>\n\n    <\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_medium\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_auto width_full\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">\n    <div class=\"brz-description-slider \">\n\n        <div class=\"bds-body \">\n            <div class=\"l-section\">\n                <div class=\"l-section-h\">\n\n                    <div class=\"bds-main-row g-cols vc_row via_grid laptops-cols_inherit tablets-cols_inherit mobiles-cols_1 valign_top type_default stacking_default\">\n                        <div class=\"wpb_column vc_column_container bds-nav-arrows-flex\">\n                            <div class=\"vc_column-inner\">\n                                <div class=\"wpb_text_column\">\n                                    <div class=\"wpb_wrapper\">\n                                        <div class=\"bds-nav-container\">\n                                            <div class=\"l-section\">\n                                                <div class=\"l-section-h\">\n                                                    <div class=\"bds-navigation-btns-column\">\n                                                        <div class=\"bds-nav-btn\">\n                                                            <span class=\"bds-nav-btn-prev icon-slider-sx color-black\"><\/span>\n                                                        <\/div>\n                                                        <div class=\"bds-nav-btn\">\n                                                            <span class=\"bds-nav-btn-next icon-slider-dx color-black\"><\/span>\n                                                        <\/div>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                        <div class=\"wpb_column vc_column_container\">\n                            <div class=\"vc_column-inner\">\n                                <div class=\"wpb_text_column\">\n                                    <div class=\"wpb_wrapper bds-slider-container color-black\">\n\n                                        <div class=\"bds-slider\">\n\n                                                                                    \n                                            <div class=\"bds-item\">\n                                                <div class=\"bds-item-flex\">\n                                                    \n                                                    <div class=\"bds-item-image\">\n                                                                                                                <img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"794\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_coll_mood_plus_burners.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_coll_mood_plus_burners.jpg 1000w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_coll_mood_plus_burners-300x238.jpg 300w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_coll_mood_plus_burners-180x143.jpg 180w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>                                                                                                            <\/div>\n                                                    \n                                                    <div class=\"bds-item-text\">\n                                                                                                                <h4 class=\"h4\">FLAT ECO-DESIGN BURNERS<\/h4>                                                        \n                                                                                                                <p class=\"p2\">The special design of the Flat Eco-design burners generates a vertical flame, to give more efficiency, reduced consumption, less heat dispersion and evenly cooked food. The 4mm thick extraordinary hob allows professional quality results.<\/p>    \n                                                        \n                                                                                                            <\/div>\n\n                                                <\/div>\n                                            <\/div>\n                                    \n                                                                                    \n                                            <div class=\"bds-item\">\n                                                <div class=\"bds-item-flex\">\n                                                    \n                                                    <div class=\"bds-item-image\">\n                                                                                                                <img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"794\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_coll_mood_plus_hobs-steel.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_coll_mood_plus_hobs-steel.jpg 1000w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_coll_mood_plus_hobs-steel-300x238.jpg 300w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_coll_mood_plus_hobs-steel-180x143.jpg 180w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>                                                                                                            <\/div>\n                                                    \n                                                    <div class=\"bds-item-text\">\n                                                                                                                <h4 class=\"h4\">4MM STAINLESS STEEL<\/h4>                                                        \n                                                                                                                <p class=\"p2\">Solid stainless steel 4 millimetres thick is the main design feature of this refined line. Each single element, from sink to hob and hood contributes to its uniqueness.<\/p>    \n                                                        \n                                                                                                            <\/div>\n\n                                                <\/div>\n                                            <\/div>\n                                    \n                                                                                    \n                                            <div class=\"bds-item\">\n                                                <div class=\"bds-item-flex\">\n                                                    \n                                                    <div class=\"bds-item-image\">\n                                                                                                                <img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"794\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_coll_mood_plus_hobs-glass.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_coll_mood_plus_hobs-glass.jpg 1000w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_coll_mood_plus_hobs-glass-300x238.jpg 300w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_coll_mood_plus_hobs-glass-180x143.jpg 180w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>                                                                                                            <\/div>\n                                                    \n                                                    <div class=\"bds-item-text\">\n                                                                                                                <h4 class=\"h4\">GLASS CERAMIC HOBS<\/h4>                                                        \n                                                                                                                <p class=\"p2\">A black or white glass ceramic hob, with superb aesthetic and functional features. Its ductility allows the Flat Eco-design burners to create great effect.<\/p>    \n                                                        \n                                                                                                            <\/div>\n\n                                                <\/div>\n                                            <\/div>\n                                    \n                                        \n                                        <\/div>\n\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n\n                <\/div>\n            <\/div>\n        <\/div>\n\n        <div class=\"bds-footer\">\n            <div class=\"l-section\">\n                <div class=\"l-section-h\">\n                    <div class=\"bds-nav-dots-wrapper \">\n                        <div class=\"bds-nav-dots\">\n                                                        <div class=\"bds-nav-dot-item slider-navigation-bar-active\" data-index=\"0\">\n                                <div class=\"slider-navigation-bar color-black\"><\/div>\n                            <\/div>\n                                                        <div class=\"bds-nav-dot-item \" data-index=\"1\">\n                                <div class=\"slider-navigation-bar color-black\"><\/div>\n                            <\/div>\n                                                        <div class=\"bds-nav-dot-item \" data-index=\"2\">\n                                <div class=\"slider-navigation-bar color-black\"><\/div>\n                            <\/div>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n\n    <\/div>\n\n    <\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_small width_full\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">[vc_empty_space]\n    <div class=\"brz-description-slider \">\n\n        <div class=\"bds-body bds-images-at-left\">\n            <div class=\"l-section\">\n                <div class=\"l-section-h\">\n\n                    <div class=\"bds-main-row g-cols vc_row via_grid laptops-cols_inherit tablets-cols_inherit mobiles-cols_1 valign_top type_default stacking_default\">\n                        <div class=\"wpb_column vc_column_container bds-nav-arrows-flex\">\n                            <div class=\"vc_column-inner\">\n                                <div class=\"wpb_text_column\">\n                                    <div class=\"wpb_wrapper\">\n                                        <div class=\"bds-nav-container\">\n                                            <div class=\"l-section\">\n                                                <div class=\"l-section-h\">\n                                                    <div class=\"bds-navigation-btns-column\">\n                                                        <div class=\"bds-nav-btn\">\n                                                            <span class=\"bds-nav-btn-prev icon-slider-sx color-black\"><\/span>\n                                                        <\/div>\n                                                        <div class=\"bds-nav-btn\">\n                                                            <span class=\"bds-nav-btn-next icon-slider-dx color-black\"><\/span>\n                                                        <\/div>\n                                                    <\/div>\n                                                <\/div>\n                                            <\/div>\n                                        <\/div>\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                        <div class=\"wpb_column vc_column_container\">\n                            <div class=\"vc_column-inner\">\n                                <div class=\"wpb_text_column\">\n                                    <div class=\"wpb_wrapper bds-slider-container color-black\">\n\n                                        <div class=\"bds-slider\">\n\n                                                                                    \n                                            <div class=\"bds-item\">\n                                                <div class=\"bds-item-flex\">\n                                                    \n                                                    <div class=\"bds-item-image\">\n                                                                                                                <img loading=\"lazy\" decoding=\"async\" width=\"945\" height=\"750\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_coll_mood_plus_sinks.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_coll_mood_plus_sinks.jpg 945w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_coll_mood_plus_sinks-300x238.jpg 300w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_coll_mood_plus_sinks-180x143.jpg 180w\" sizes=\"auto, (max-width: 945px) 100vw, 945px\" \/>                                                                                                            <\/div>\n                                                    \n                                                    <div class=\"bds-item-text\">\n                                                                                                                <h4 class=\"h4\">SINKS, PERFECT EXAMPLE OF PURITY<\/h4>                                                        \n                                                                                                                <p class=\"p2\">Capacious bowls plus a uniquely designed sculpted drainer, a sloping channel in the material, extending beyond the edge into the cavity, opening up a new path for water flow.<\/p>    \n                                                        \n                                                                                                            <\/div>\n\n                                                <\/div>\n                                            <\/div>\n                                    \n                                                                                    \n                                            <div class=\"bds-item\">\n                                                <div class=\"bds-item-flex\">\n                                                    \n                                                    <div class=\"bds-item-image\">\n                                                                                                                <img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"794\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_coll_mood_plus_taps.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_coll_mood_plus_taps.jpg 1000w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_coll_mood_plus_taps-300x238.jpg 300w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_coll_mood_plus_taps-180x143.jpg 180w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>                                                                                                            <\/div>\n                                                    \n                                                    <div class=\"bds-item-text\">\n                                                                                                                <h4 class=\"h4\">STAINLESS STEEL TAPS<\/h4>                                                        \n                                                                                                                <p class=\"p2\">A tap like a line: precise, direct, graceful. The AISI 316 stainless steel makes it even more corrosion resistant. The minimum thickness guarantees a sustained flow as well as easiness of use.<\/p>    \n                                                        \n                                                                                                            <\/div>\n\n                                                <\/div>\n                                            <\/div>\n                                    \n                                                                                    \n                                            <div class=\"bds-item\">\n                                                <div class=\"bds-item-flex\">\n                                                    \n                                                    <div class=\"bds-item-image\">\n                                                                                                                <img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"793\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_coll_mood_plus_cooker-hood.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_coll_mood_plus_cooker-hood.jpg 1000w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_coll_mood_plus_cooker-hood-300x238.jpg 300w, https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/08\/Barazza_coll_mood_plus_cooker-hood-180x143.jpg 180w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/>                                                                                                            <\/div>\n                                                    \n                                                    <div class=\"bds-item-text\">\n                                                                                                                <h4 class=\"h4\">MINIMAL COOKER HOOD<\/h4>                                                        \n                                                                                                                <p class=\"p2\">An essential design and advanced functions add substance to a hood offering faultless removal of smells and steam. The air is quickly refreshed to ensure the kitchen remains the place of taste and hospitality.<\/p>    \n                                                        \n                                                                                                            <\/div>\n\n                                                <\/div>\n                                            <\/div>\n                                    \n                                        \n                                        <\/div>\n\n                                    <\/div>\n                                <\/div>\n                            <\/div>\n                        <\/div>\n                    <\/div>\n\n                <\/div>\n            <\/div>\n        <\/div>\n\n        <div class=\"bds-footer\">\n            <div class=\"l-section\">\n                <div class=\"l-section-h\">\n                    <div class=\"bds-nav-dots-wrapper bds-nav-left-align\">\n                        <div class=\"bds-nav-dots\">\n                                                        <div class=\"bds-nav-dot-item slider-navigation-bar-active\" data-index=\"0\">\n                                <div class=\"slider-navigation-bar color-black\"><\/div>\n                            <\/div>\n                                                        <div class=\"bds-nav-dot-item \" data-index=\"1\">\n                                <div class=\"slider-navigation-bar color-black\"><\/div>\n                            <\/div>\n                                                        <div class=\"bds-nav-dot-item \" data-index=\"2\">\n                                <div class=\"slider-navigation-bar color-black\"><\/div>\n                            <\/div>\n                                                    <\/div>\n                    <\/div>\n                <\/div>\n            <\/div>\n        <\/div>\n\n    <\/div>\n\n    <\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_medium\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row height_small\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\"><div class=\"wpb_text_column\"><div class=\"wpb_wrapper\"><p class=\"p1\"><strong>MOOD product ranges<\/strong><\/p>\n<\/div><\/div><\/div><\/div><\/div><\/div><\/div><\/section><section class=\"l-section wpb_row us_custom_63e7dc02 height_auto width_full\"><div class=\"l-section-h i-cf\"><div class=\"g-cols vc_row via_flex valign_top type_default stacking_default\"><div class=\"vc_col-sm-12 wpb_column vc_column_container\"><div class=\"vc_column-inner\"><div class=\"wpb_wrapper\">    \n    <div class=\"tab-component dark-version tab-version\">\n        <div class=\"l-section-h\">\n            <div class=\"tab-container\">\n                <div\n                class=\"nav-arrow icon-slider-sx position-absolute start-0 top-50 translate-middle-y z-1 d-none\"\n                ><\/div>\n                <ul class=\"category-list\">\n                                        <li class=\"category-item\" data-tab-id=\"tab-6a97be52c87f8\" data-category=\"hobs\">\n                            <a href=\"#\" role=\"tab\" aria-selected=\"false\">\n                                                            <div class=\"icon-circle\">\n                                    <img decoding=\"async\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/07\/Barazza_Gamme_Piani-cottura.svg\" alt=\"Icona raffigurante un piano cottura stilizzato all'interno di un cerchio.\" \/>\n                                <\/div>\n                                                            <p class=\"category-name mt-1 p1\" >HOBS<\/p>\n                            <\/a>\n                        <\/li>\n                                            <li class=\"category-item\" data-tab-id=\"tab-6a97be52c88cb\" data-category=\"hoods\">\n                            <a href=\"#\" role=\"tab\" aria-selected=\"false\">\n                                                            <div class=\"icon-circle\">\n                                    <img decoding=\"async\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/07\/Barazza_Gamme_Cappe.svg\" alt=\"Icona raffigurante una cappa aspirante all'interno di un cerchio.\" \/>\n                                <\/div>\n                                                            <p class=\"category-name mt-1 p1\" >HOODS<\/p>\n                            <\/a>\n                        <\/li>\n                                            <li class=\"category-item\" data-tab-id=\"tab-6a97be52c8985\" data-category=\"stainless steel sinks and square bowls\">\n                            <a href=\"#\" role=\"tab\" aria-selected=\"false\">\n                                                            <div class=\"icon-circle\">\n                                    <img decoding=\"async\" src=\"https:\/\/barazzasrl.it\/wp-content\/uploads\/2025\/07\/Barazza_Gamme_Lavandini.svg\" alt=\"Icona raffigurante un lavello stilizzato all'interno di un cerchio.\" \/>\n                                <\/div>\n                                                            <p class=\"category-name mt-1 p1\" >STAINLESS STEEL SINKS AND SQUARE BOWLS<\/p>\n                            <\/a>\n                        <\/li>\n                       \n                <\/ul>\n                <div class=\"nav-arrow icon-slider-dx position-absolute end-0 top-50 translate-middle-y z-1\"><\/div>\n            <\/div>\n        <\/div>\n    <\/div>\n\n    <div class=\"tab-container-content\" >\n            <div class=\"tab-content d-none\" id=\"tab-6a97be52c87f8\">\n        <div class=\"l-section-h\">\n            [vc_empty_space height=&#8221;50px&#8221;]<div class=\"wpb_text_column us_custom_b85e11a6\"><div class=\"wpb_wrapper\"><h2>HOBS<br \/>\n<em>MOOD <\/em>COLLECTION<\/h2>\n<\/div><\/div>[vc_empty_space]\n    <div class=\"brz-product-carousel \">\n\n        <div class=\"l-section\">\n            <div class=\"l-section-h\">\n\n                <div class=\"bpc-slider-nav color-black\">\n\n                <\/div>\n\n                <div class=\"bpc-slider\" data-autoscroll=\"true\">\n\n                                                                            <div class=\"bpc-item\">\n\n                                                                    <a class=\"bcp-item-image-a\" href=\"https:\/\/barazzasrl.it\/en\/prodotto\/65-cm-mood-built-in-hob\/\" target=\"_blank\">\n                                    \n                                    <img decoding=\"async\" src=\"https:\/\/barazzasrl.it\/prodotti\/img\/foto-prodotto\/372_372\/1PMD64.png\" onerror=\"this.src='https:\/\/barazzasrl.it\/wp-content\/plugins\/c21-products-importer\/assets\/placeholder-image.png'\" alt=\"Product image 1PMD64\" \/>\n\n                                                                        <\/a>\n                                \n\n                                <div class=\"bpc-item-container bpc-item-text color-white\">\n                                                                            <a href=\"https:\/\/barazzasrl.it\/en\/prodotto\/65-cm-mood-built-in-hob\/\" target=\"_blank\">\n                                                                                <h4 class=\"h4\">65 cm Mood built-in hob<\/h4>                                                                                <\/a>\n                                    \n                                                                            <div class=\"bpc-item-description\">\n                                            <p class=\"p1\">1PMD64<\/p>\n                                        <\/div>\n                                                                    <\/div>\n\n                            <\/div>\n                                                                            <div class=\"bpc-item\">\n\n                                                                    <a class=\"bcp-item-image-a\" href=\"https:\/\/barazzasrl.it\/en\/prodotto\/75-cm-mood-built-in-hob-for-60-cm-base\/\" target=\"_blank\">\n                                    \n                                    <img decoding=\"async\" src=\"https:\/\/barazzasrl.it\/prodotti\/img\/foto-prodotto\/372_372\/1PMD70.png\" onerror=\"this.src='https:\/\/barazzasrl.it\/wp-content\/plugins\/c21-products-importer\/assets\/placeholder-image.png'\" alt=\"Product image 1PMD70\" \/>\n\n                                                                        <\/a>\n                                \n\n                                <div class=\"bpc-item-container bpc-item-text color-white\">\n                                                                            <a href=\"https:\/\/barazzasrl.it\/en\/prodotto\/75-cm-mood-built-in-hob-for-60-cm-base\/\" target=\"_blank\">\n                                                                                <h4 class=\"h4\">75 cm Mood built-in hob for 60 cmbase<\/h4>                                                                                <\/a>\n                                    \n                                                                            <div class=\"bpc-item-description\">\n                                            <p class=\"p1\">1PMD70<\/p>\n                                        <\/div>\n                                                                    <\/div>\n\n                            <\/div>\n                                                                            <div class=\"bpc-item\">\n\n                                                                    <a class=\"bcp-item-image-a\" href=\"https:\/\/barazzasrl.it\/en\/prodotto\/75-cm-mood-built-in-hob\/\" target=\"_blank\">\n                                    \n                                    <img decoding=\"async\" src=\"https:\/\/barazzasrl.it\/prodotti\/img\/foto-prodotto\/372_372\/1PMD75.png\" onerror=\"this.src='https:\/\/barazzasrl.it\/wp-content\/plugins\/c21-products-importer\/assets\/placeholder-image.png'\" alt=\"Product image 1PMD75\" \/>\n\n                                                                        <\/a>\n                                \n\n                                <div class=\"bpc-item-container bpc-item-text color-white\">\n                                                                            <a href=\"https:\/\/barazzasrl.it\/en\/prodotto\/75-cm-mood-built-in-hob\/\" target=\"_blank\">\n                                                                                <h4 class=\"h4\">75 cm Mood built-in hob<\/h4>                                                                                <\/a>\n                                    \n                                                                            <div class=\"bpc-item-description\">\n                                            <p class=\"p1\">1PMD75<\/p>\n                                        <\/div>\n                                                                    <\/div>\n\n                            <\/div>\n                                                                            <div class=\"bpc-item\">\n\n                                                                    <a class=\"bcp-item-image-a\" href=\"https:\/\/barazzasrl.it\/en\/prodotto\/90-cm-mood-built-in-hob\/\" target=\"_blank\">\n                                    \n                                    <img decoding=\"async\" src=\"https:\/\/barazzasrl.it\/prodotti\/img\/foto-prodotto\/372_372\/1PMD95.png\" onerror=\"this.src='https:\/\/barazzasrl.it\/wp-content\/plugins\/c21-products-importer\/assets\/placeholder-image.png'\" alt=\"Product image 1PMD95\" \/>\n\n                                                                        <\/a>\n                                \n\n                                <div class=\"bpc-item-container bpc-item-text color-white\">\n                                                                            <a href=\"https:\/\/barazzasrl.it\/en\/prodotto\/90-cm-mood-built-in-hob\/\" target=\"_blank\">\n                                                                                <h4 class=\"h4\">90 cm Mood built-in hob<\/h4>                                                                                <\/a>\n                                    \n                                                                            <div class=\"bpc-item-description\">\n                                            <p class=\"p1\">1PMD95<\/p>\n                                        <\/div>\n                                                                    <\/div>\n\n                            <\/div>\n                                                                            <div class=\"bpc-item\">\n\n                                                                    <a class=\"bcp-item-image-a\" href=\"https:\/\/barazzasrl.it\/en\/prodotto\/110-cm-mood-built-in-hob\/\" target=\"_blank\">\n                                    \n                                    <img decoding=\"async\" src=\"https:\/\/barazzasrl.it\/prodotti\/img\/foto-prodotto\/372_372\/1PMD104.png\" onerror=\"this.src='https:\/\/barazzasrl.it\/wp-content\/plugins\/c21-products-importer\/assets\/placeholder-image.png'\" alt=\"Product image 1PMD104\" \/>\n\n                                                                        <\/a>\n                                \n\n                                <div class=\"bpc-item-container bpc-item-text color-white\">\n                                                                            <a href=\"https:\/\/barazzasrl.it\/en\/prodotto\/110-cm-mood-built-in-hob\/\" target=\"_blank\">\n                                                                                <h4 class=\"h4\">110 cm Mood built-in hob<\/h4>                                                                                <\/a>\n                                    \n                                                                            <div class=\"bpc-item-description\">\n                                            <p class=\"p1\">1PMD104<\/p>\n                                        <\/div>\n                                                                    <\/div>\n\n                            <\/div>\n                                                                            <div class=\"bpc-item\">\n\n                                                                    <a class=\"bcp-item-image-a\" href=\"https:\/\/barazzasrl.it\/en\/prodotto\/75-cm-mood-built-in-hob-for-60-cm-base-2\/\" target=\"_blank\">\n                                    \n                                    <img decoding=\"async\" src=\"https:\/\/barazzasrl.it\/prodotti\/img\/foto-prodotto\/372_372\/1PMD70B.png\" onerror=\"this.src='https:\/\/barazzasrl.it\/wp-content\/plugins\/c21-products-importer\/assets\/placeholder-image.png'\" alt=\"Product image 1PMD70B\" \/>\n\n                                                                        <\/a>\n                                \n\n                                <div class=\"bpc-item-container bpc-item-text color-white\">\n                                                                            <a href=\"https:\/\/barazzasrl.it\/en\/prodotto\/75-cm-mood-built-in-hob-for-60-cm-base-2\/\" target=\"_blank\">\n                                                                                <h4 class=\"h4\">75 cm Mood built-in hob for 60 cmbase<\/h4>                                                                                <\/a>\n                                    \n                                                                            <div class=\"bpc-item-description\">\n                                            <p class=\"p1\">1PMD70B<\/p>\n                                        <\/div>\n                                                                    <\/div>\n\n                            <\/div>\n                                                                            <div class=\"bpc-item\">\n\n                                                                    <a class=\"bcp-item-image-a\" href=\"https:\/\/barazzasrl.it\/en\/prodotto\/90-cm-mood-built-in-hob-2\/\" target=\"_blank\">\n                                    \n                                    <img decoding=\"async\" src=\"https:\/\/barazzasrl.it\/prodotti\/img\/foto-prodotto\/372_372\/1PMD95B.png\" onerror=\"this.src='https:\/\/barazzasrl.it\/wp-content\/plugins\/c21-products-importer\/assets\/placeholder-image.png'\" alt=\"Product image 1PMD95B\" \/>\n\n                                                                        <\/a>\n                                \n\n                                <div class=\"bpc-item-container bpc-item-text color-white\">\n                                                                            <a href=\"https:\/\/barazzasrl.it\/en\/prodotto\/90-cm-mood-built-in-hob-2\/\" target=\"_blank\">\n                                                                                <h4 class=\"h4\">90 cm Mood built-in hob<\/h4>                                                                                <\/a>\n                                    \n                                                                            <div class=\"bpc-item-description\">\n                                            <p class=\"p1\">1PMD95B<\/p>\n                                        <\/div>\n                                                                    <\/div>\n\n                            <\/div>\n                                                                            <div class=\"bpc-item\">\n\n                                                                    <a class=\"bcp-item-image-a\" href=\"https:\/\/barazzasrl.it\/en\/prodotto\/65-cm-mood-built-in-hob-2\/\" target=\"_blank\">\n                                    \n                                    <img decoding=\"async\" src=\"https:\/\/barazzasrl.it\/prodotti\/img\/foto-prodotto\/372_372\/1PMD64N.png\" onerror=\"this.src='https:\/\/barazzasrl.it\/wp-content\/plugins\/c21-products-importer\/assets\/placeholder-image.png'\" alt=\"Product image 1PMD64N\" \/>\n\n                                                                        <\/a>\n                                \n\n                                <div class=\"bpc-item-container bpc-item-text color-white\">\n                                                                            <a href=\"https:\/\/barazzasrl.it\/en\/prodotto\/65-cm-mood-built-in-hob-2\/\" target=\"_blank\">\n                                                                                <h4 class=\"h4\">65 cm Mood built-in hob<\/h4>                                                                                <\/a>\n                                    \n                                                                            <div class=\"bpc-item-description\">\n                                            <p class=\"p1\">1PMD64N<\/p>\n                                        <\/div>\n                                                                    <\/div>\n\n                            <\/div>\n                                                                            <div class=\"bpc-item\">\n\n                                                                    <a class=\"bcp-item-image-a\" href=\"https:\/\/barazzasrl.it\/en\/prodotto\/75-cm-mood-built-in-hob-for-60-cm-base-3\/\" target=\"_blank\">\n                                    \n                                    <img decoding=\"async\" src=\"https:\/\/barazzasrl.it\/prodotti\/img\/foto-prodotto\/372_372\/1PMD70N.png\" onerror=\"this.src='https:\/\/barazzasrl.it\/wp-content\/plugins\/c21-products-importer\/assets\/placeholder-image.png'\" alt=\"Product image 1PMD70N\" \/>\n\n                                                                        <\/a>\n                                \n\n                                <div class=\"bpc-item-container bpc-item-text color-white\">\n                                                                            <a href=\"https:\/\/barazzasrl.it\/en\/prodotto\/75-cm-mood-built-in-hob-for-60-cm-base-3\/\" target=\"_blank\">\n                                                                                <h4 class=\"h4\">75 cm Mood built-in hob for 60 cmbase<\/h4>                                                                                <\/a>\n                                    \n                                                                            <div class=\"bpc-item-description\">\n                                            <p class=\"p1\">1PMD70N<\/p>\n                                        <\/div>\n                                                                    <\/div>\n\n                            <\/div>\n                                                                            <div class=\"bpc-item\">\n\n                                                                    <a class=\"bcp-item-image-a\" href=\"https:\/\/barazzasrl.it\/en\/prodotto\/90-cm-mood-built-in-hob-3\/\" target=\"_blank\">\n                                    \n                                    <img decoding=\"async\" src=\"https:\/\/barazzasrl.it\/prodotti\/img\/foto-prodotto\/372_372\/1PMD95N.png\" onerror=\"this.src='https:\/\/barazzasrl.it\/wp-content\/plugins\/c21-products-importer\/assets\/placeholder-image.png'\" alt=\"Product image 1PMD95N\" \/>\n\n                                                                        <\/a>\n                                \n\n                                <div class=\"bpc-item-container bpc-item-text color-white\">\n                                                                            <a href=\"https:\/\/barazzasrl.it\/en\/prodotto\/90-cm-mood-built-in-hob-3\/\" target=\"_blank\">\n                                                                                <h4 class=\"h4\">90 cm Mood built-in hob<\/h4>                                                                                <\/a>\n                                    \n                                                                            <div class=\"bpc-item-description\">\n                                            <p class=\"p1\">1PMD95N<\/p>\n                                        <\/div>\n                                                                    <\/div>\n\n                            <\/div>\n                                                                            <div class=\"bpc-item\">\n\n                                                                    <a class=\"bcp-item-image-a\" href=\"https:\/\/barazzasrl.it\/en\/prodotto\/110-cm-mood-built-in-hob-2\/\" target=\"_blank\">\n                                    \n                                    <img decoding=\"async\" src=\"https:\/\/barazzasrl.it\/prodotti\/img\/foto-prodotto\/372_372\/1PMD104N.png\" onerror=\"this.src='https:\/\/barazzasrl.it\/wp-content\/plugins\/c21-products-importer\/assets\/placeholder-image.png'\" alt=\"Product image 1PMD104N\" \/>\n\n                                                                        <\/a>\n                                \n\n                                <div class=\"bpc-item-container bpc-item-text color-white\">\n                                                                            <a href=\"https:\/\/barazzasrl.it\/en\/prodotto\/110-cm-mood-built-in-hob-2\/\" target=\"_blank\">\n                                                                                <h4 class=\"h4\">110 cm Mood built-in hob<\/h4>                                                                                <\/a>\n                                    \n                                                                            <div class=\"bpc-item-description\">\n                                            <p class=\"p1\">1PMD104N<\/p>\n                                        <\/div>\n                                                                    <\/div>\n\n                            <\/div>\n                    \n                <\/div>\n\n            <\/div>\n        <\/div>\n\n    <\/div>\n\n[vc_empty_space height=&#8221;130px&#8221;]        <\/div>\n    <\/div>\n        <div class=\"tab-content d-none\" id=\"tab-6a97be52c88cb\">\n        <div class=\"l-section-h\">\n            [vc_empty_space height=&#8221;50px&#8221;]<div class=\"wpb_text_column us_custom_b85e11a6\"><div class=\"wpb_wrapper\"><h2>HOODS<br \/>\n<em>MOOD <\/em>COLLECTION<\/h2>\n<\/div><\/div>[vc_empty_space]\n    <div class=\"brz-product-carousel \">\n\n        <div class=\"l-section\">\n            <div class=\"l-section-h\">\n\n                <div class=\"bpc-slider-nav color-black\">\n\n                <\/div>\n\n                <div class=\"bpc-slider\" data-autoscroll=\"true\">\n\n                                                                            <div class=\"bpc-item\">\n\n                                                                    <a class=\"bcp-item-image-a\" href=\"https:\/\/barazzasrl.it\/en\/prodotto\/90-cm-mood-wall-cooker-hood\/\" target=\"_blank\">\n                                    \n                                    <img decoding=\"async\" src=\"https:\/\/barazzasrl.it\/prodotti\/img\/foto-prodotto\/372_372\/1KMDP9.png\" onerror=\"this.src='https:\/\/barazzasrl.it\/wp-content\/plugins\/c21-products-importer\/assets\/placeholder-image.png'\" alt=\"Product image 1KMDP9\" \/>\n\n                                                                        <\/a>\n                                \n\n                                <div class=\"bpc-item-container bpc-item-text color-white\">\n                                                                            <a href=\"https:\/\/barazzasrl.it\/en\/prodotto\/90-cm-mood-wall-cooker-hood\/\" target=\"_blank\">\n                                                                                <h4 class=\"h4\">90 cm Mood wall cooker hood<\/h4>                                                                                <\/a>\n                                    \n                                                                            <div class=\"bpc-item-description\">\n                                            <p class=\"p1\">1KMDP9<\/p>\n                                        <\/div>\n                                                                    <\/div>\n\n                            <\/div>\n                                                                            <div class=\"bpc-item\">\n\n                                                                    <a class=\"bcp-item-image-a\" href=\"https:\/\/barazzasrl.it\/en\/prodotto\/120-cm-mood-wall-cooker-hood\/\" target=\"_blank\">\n                                    \n                                    <img decoding=\"async\" src=\"https:\/\/barazzasrl.it\/prodotti\/img\/foto-prodotto\/372_372\/1KMDP12.png\" onerror=\"this.src='https:\/\/barazzasrl.it\/wp-content\/plugins\/c21-products-importer\/assets\/placeholder-image.png'\" alt=\"Product image 1KMDP12\" \/>\n\n                                                                        <\/a>\n                                \n\n                                <div class=\"bpc-item-container bpc-item-text color-white\">\n                                                                            <a href=\"https:\/\/barazzasrl.it\/en\/prodotto\/120-cm-mood-wall-cooker-hood\/\" target=\"_blank\">\n                                                                                <h4 class=\"h4\">120 cm Mood wall cooker hood<\/h4>                                                                                <\/a>\n                                    \n                                                                            <div class=\"bpc-item-description\">\n                                            <p class=\"p1\">1KMDP12<\/p>\n                                        <\/div>\n                                                                    <\/div>\n\n                            <\/div>\n                    \n                <\/div>\n\n            <\/div>\n        <\/div>\n\n    <\/div>\n\n[vc_empty_space height=&#8221;130px&#8221;]        <\/div>\n    <\/div>\n        <div class=\"tab-content d-none\" id=\"tab-6a97be52c8985\">\n        <div class=\"l-section-h\">\n            [vc_empty_space height=&#8221;50px&#8221;]<div class=\"wpb_text_column us_custom_b85e11a6\"><div class=\"wpb_wrapper\"><h2>STAINLESS STEEL SINKS AND SQUARE BOWLS<br \/>\n<em>MOOD <\/em>COLLECTION<\/h2>\n<\/div><\/div>[vc_empty_space]\n    <div class=\"brz-product-carousel \">\n\n        <div class=\"l-section\">\n            <div class=\"l-section-h\">\n\n                <div class=\"bpc-slider-nav color-black\">\n\n                <\/div>\n\n                <div class=\"bpc-slider\" data-autoscroll=\"true\">\n\n                                                                            <div class=\"bpc-item\">\n\n                                                                    <a class=\"bcp-item-image-a\" href=\"https:\/\/barazzasrl.it\/en\/prodotto\/86x51-cm-mood-built-in-sink\/\" target=\"_blank\">\n                                    \n                                    <img decoding=\"async\" src=\"https:\/\/barazzasrl.it\/prodotti\/img\/foto-prodotto\/372_372\/1LMD91D.png\" onerror=\"this.src='https:\/\/barazzasrl.it\/wp-content\/plugins\/c21-products-importer\/assets\/placeholder-image.png'\" alt=\"Product image 1LMDR91D\" \/>\n\n                                                                        <\/a>\n                                \n\n                                <div class=\"bpc-item-container bpc-item-text color-white\">\n                                                                            <a href=\"https:\/\/barazzasrl.it\/en\/prodotto\/86x51-cm-mood-built-in-sink\/\" target=\"_blank\">\n                                                                                <h4 class=\"h4\">86x51 cm Mood built-in sink<\/h4>                                                                                <\/a>\n                                    \n                                                                            <div class=\"bpc-item-description\">\n                                            <p class=\"p1\">1LMDR91D<\/p>\n                                        <\/div>\n                                                                    <\/div>\n\n                            <\/div>\n                                                                            <div class=\"bpc-item\">\n\n                                                                    <a class=\"bcp-item-image-a\" href=\"https:\/\/barazzasrl.it\/en\/prodotto\/86x51-cm-mood-built-in-sink-2\/\" target=\"_blank\">\n                                    \n                                    <img decoding=\"async\" src=\"https:\/\/barazzasrl.it\/prodotti\/img\/foto-prodotto\/372_372\/1LMD91S.png\" onerror=\"this.src='https:\/\/barazzasrl.it\/wp-content\/plugins\/c21-products-importer\/assets\/placeholder-image.png'\" alt=\"Product image 1LMDR91S\" \/>\n\n                                                                        <\/a>\n                                \n\n                                <div class=\"bpc-item-container bpc-item-text color-white\">\n                                                                            <a href=\"https:\/\/barazzasrl.it\/en\/prodotto\/86x51-cm-mood-built-in-sink-2\/\" target=\"_blank\">\n                                                                                <h4 class=\"h4\">86x51 cm Mood built-in sink<\/h4>                                                                                <\/a>\n                                    \n                                                                            <div class=\"bpc-item-description\">\n                                            <p class=\"p1\">1LMDR91S<\/p>\n                                        <\/div>\n                                                                    <\/div>\n\n                            <\/div>\n                                                                            <div class=\"bpc-item\">\n\n                                                                    <a class=\"bcp-item-image-a\" href=\"https:\/\/barazzasrl.it\/en\/prodotto\/86x51-cm-mood-built-in-sink-3\/\" target=\"_blank\">\n                                    \n                                    <img decoding=\"async\" src=\"https:\/\/barazzasrl.it\/prodotti\/img\/foto-prodotto\/372_372\/1LMD92.png\" onerror=\"this.src='https:\/\/barazzasrl.it\/wp-content\/plugins\/c21-products-importer\/assets\/placeholder-image.png'\" alt=\"Product image 1LMDR92\" \/>\n\n                                                                        <\/a>\n                                \n\n                                <div class=\"bpc-item-container bpc-item-text color-white\">\n                                                                            <a href=\"https:\/\/barazzasrl.it\/en\/prodotto\/86x51-cm-mood-built-in-sink-3\/\" target=\"_blank\">\n                                                                                <h4 class=\"h4\">86x51 cm Mood built-in sink<\/h4>                                                                                <\/a>\n                                    \n                                                                            <div class=\"bpc-item-description\">\n                                            <p class=\"p1\">1LMDR92<\/p>\n                                        <\/div>\n                                                                    <\/div>\n\n                            <\/div>\n                                                                            <div class=\"bpc-item\">\n\n                                                                    <a class=\"bcp-item-image-a\" href=\"https:\/\/barazzasrl.it\/en\/prodotto\/86x51-cm-mood-built-in-sink-4\/\" target=\"_blank\">\n                                    \n                                    <img decoding=\"async\" src=\"https:\/\/barazzasrl.it\/prodotti\/img\/foto-prodotto\/372_372\/1LMDR91.png\" onerror=\"this.src='https:\/\/barazzasrl.it\/wp-content\/plugins\/c21-products-importer\/assets\/placeholder-image.png'\" alt=\"Product image 1LMDR91\" \/>\n\n                                                                        <\/a>\n                                \n\n                                <div class=\"bpc-item-container bpc-item-text color-white\">\n                                                                            <a href=\"https:\/\/barazzasrl.it\/en\/prodotto\/86x51-cm-mood-built-in-sink-4\/\" target=\"_blank\">\n                                                                                <h4 class=\"h4\">86x51 cm Mood built-in sink<\/h4>                                                                                <\/a>\n                                    \n                                                                            <div class=\"bpc-item-description\">\n                                            <p class=\"p1\">1LMDR91<\/p>\n                                        <\/div>\n                                                                    <\/div>\n\n                            <\/div>\n                    \n                <\/div>\n\n            <\/div>\n        <\/div>\n\n    <\/div>\n\n[vc_empty_space height=&#8221;130px&#8221;]        <\/div>\n    <\/div>\n        <\/div>\n    <\/div><\/div><\/div><\/div><\/div><\/section>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":104734,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"inline_featured_image":false,"footnotes":""},"class_list":["post-104835","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.4 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mood - Barazza SRL<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/barazzasrl.it\/en\/collections\/mood\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mood - Barazza SRL\" \/>\n<meta property=\"og:url\" content=\"https:\/\/barazzasrl.it\/en\/collections\/mood\/\" \/>\n<meta property=\"og:site_name\" content=\"Barazza SRL\" \/>\n<meta property=\"article:modified_time\" content=\"2025-12-12T10:30:55+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/barazzasrl.it\/en\/collections\/mood\/\",\"url\":\"https:\/\/barazzasrl.it\/en\/collections\/mood\/\",\"name\":\"Mood - Barazza SRL\",\"isPartOf\":{\"@id\":\"https:\/\/barazzasrl.it\/#website\"},\"datePublished\":\"2025-07-31T12:07:23+00:00\",\"dateModified\":\"2025-12-12T10:30:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/barazzasrl.it\/en\/collections\/mood\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/barazzasrl.it\/en\/collections\/mood\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/barazzasrl.it\/en\/collections\/mood\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/barazzasrl.it\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Collections\",\"item\":\"https:\/\/barazzasrl.it\/en\/collections\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Mood\",\"item\":\"https:\/\/barazzasrl.it\/en\/product-range\/hoods\/barazza_gamme_piani-cottura-2\/\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/barazzasrl.it\/#website\",\"url\":\"https:\/\/barazzasrl.it\/\",\"name\":\"Barazza SRL\",\"description\":\"Taste of Design\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/barazzasrl.it\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mood - Barazza SRL","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/barazzasrl.it\/en\/collections\/mood\/","og_locale":"en_US","og_type":"article","og_title":"Mood - Barazza SRL","og_url":"https:\/\/barazzasrl.it\/en\/collections\/mood\/","og_site_name":"Barazza SRL","article_modified_time":"2025-12-12T10:30:55+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/barazzasrl.it\/en\/collections\/mood\/","url":"https:\/\/barazzasrl.it\/en\/collections\/mood\/","name":"Mood - Barazza SRL","isPartOf":{"@id":"https:\/\/barazzasrl.it\/#website"},"datePublished":"2025-07-31T12:07:23+00:00","dateModified":"2025-12-12T10:30:55+00:00","breadcrumb":{"@id":"https:\/\/barazzasrl.it\/en\/collections\/mood\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/barazzasrl.it\/en\/collections\/mood\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/barazzasrl.it\/en\/collections\/mood\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/barazzasrl.it\/en\/"},{"@type":"ListItem","position":2,"name":"Collections","item":"https:\/\/barazzasrl.it\/en\/collections\/"},{"@type":"ListItem","position":3,"name":"Mood","item":"https:\/\/barazzasrl.it\/en\/product-range\/hoods\/barazza_gamme_piani-cottura-2\/"}]},{"@type":"WebSite","@id":"https:\/\/barazzasrl.it\/#website","url":"https:\/\/barazzasrl.it\/","name":"Barazza SRL","description":"Taste of Design","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/barazzasrl.it\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/barazzasrl.it\/en\/wp-json\/wp\/v2\/pages\/104835","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/barazzasrl.it\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/barazzasrl.it\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/barazzasrl.it\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/barazzasrl.it\/en\/wp-json\/wp\/v2\/comments?post=104835"}],"version-history":[{"count":6,"href":"https:\/\/barazzasrl.it\/en\/wp-json\/wp\/v2\/pages\/104835\/revisions"}],"predecessor-version":[{"id":112652,"href":"https:\/\/barazzasrl.it\/en\/wp-json\/wp\/v2\/pages\/104835\/revisions\/112652"}],"up":[{"embeddable":true,"href":"https:\/\/barazzasrl.it\/en\/wp-json\/wp\/v2\/pages\/104734"}],"wp:attachment":[{"href":"https:\/\/barazzasrl.it\/en\/wp-json\/wp\/v2\/media?parent=104835"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}